{"id":17354,"date":"2022-12-19T16:16:21","date_gmt":"2022-12-19T15:16:21","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=17354"},"modified":"2022-12-19T16:16:24","modified_gmt":"2022-12-19T15:16:24","slug":"africa-dialoga-con-biden","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/en\/politica-geopolitica\/africa-dialoga-con-biden\/","title":{"rendered":"<strong>\u00c1frica dialoga con Biden<\/strong>"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Estados Unidos celebra su gran cumbre con los pa\u00edses africanos con grandes anuncios de inversiones y compromisos de apoyar el mayor peso internacional de un continente que en los \u00faltimos a\u00f1os se ha sentido m\u00e1s apoyado por parte de chinos y rusos<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El mandato del anterior presidente norteamericano, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Donald_Trump\" target=\"_blank\" rel=\"noreferrer noopener\">Donald Trump<\/a>, supuso para las relaciones entre \u00c1frica y los Estados Unidos no solo una especie de \u2018congelaci\u00f3n\u2019, sino todo un retroceso. Algunos l\u00edderes africanos a\u00fan recuerdan c\u00f3mo el exc\u00e9ntrico presidente, sin duda el mayor responsable de la crisis democr\u00e1tica y del descr\u00e9dito de la pol\u00edtica en que vive sumido el mundo en estos tiempos convulsos, calific\u00f3 de \u2018agujeros de mierda\u2019 a pa\u00edses centroamericanos como Hait\u00ed o los del continente africano al referirse al origen de muchos de los migrantes que intentaban acceder a los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras todo eso suced\u00eda, y con los fondos de cooperaci\u00f3n norteamericanos rebajados a su m\u00ednima expresi\u00f3n, China y Rusia avanzaban en el continente africano con estrategias muy diferentes, pero en ambos casos efectivas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">China lo hac\u00eda desde el punto de vista econ\u00f3mico, convirti\u00e9ndose en el gran prestamista y principal acreedor del continente africano, o apostando por la construcci\u00f3n de infraestructuras a cambio de recursos naturales. Lo pudimos comprobar hace muy pocos d\u00edas, cuando la <a href=\"https:\/\/casafrica.es\/es\/redes\/comunidad-economica-de-estados-de-africa-occidental-cedeao\" target=\"_blank\" rel=\"noreferrer noopener\">Comunidad Econ\u00f3mica de Estados de \u00c1frica Occidental (CEDEAO)<\/a>, el organismo que agrupa a nuestros pa\u00edses vecinos, puso la primera piedra de una flamante nueva sede en Abuya (Nigeria) que ser\u00e1 construida por los chinos y entregada \u2018llave en mano\u2019 a modo de regalo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rusia, por su parte, ha apostado por la cooperaci\u00f3n militar, bien con la venta de armas o con la presencia de soldados, propios o \u2018subcontratados\u2019 a este ej\u00e9rcito ruso paralelo que es el Grupo Wagner, que tanto conocen en pa\u00edses como Mali o la Rep\u00fablica Centroafricana. La presencia rusa, adem\u00e1s, explota claramente el objetivo de la pol\u00edtica exterior de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Vlad%C3%ADmir_Putin\" target=\"_blank\" rel=\"noreferrer noopener\">Putin<\/a>: mermar tanto como se pueda a la <a href=\"https:\/\/european-union.europa.eu\/index_es\" target=\"_blank\" rel=\"noreferrer noopener\">Uni\u00f3n Europea<\/a> o a las llamadas \u2018democracias liberales\u2019, pero eso casi que merece otro art\u00edculo aparte.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rusos y chinos ten\u00edan claro desde hace a\u00f1os que \u00c1frica est\u00e1 en el centro del mapa geopol\u00edtico mundial, y que tanto por su enorme riqueza en recursos naturales (desde petr\u00f3leo y gas a madera, pasando por oro, diamantes, cobalto, litio o el ansiado colt\u00e1n para los m\u00f3viles) como por su potencial demogr\u00e1fico (recuerden que ahora en el mundo hay un africano de cada 6 habitantes y que en 2100 ser\u00e1 uno de cada tres) hay que trabajar muy a fondo la diplomacia y afianzar los intereses a futuro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria dem\u00f3crata de <a href=\"https:\/\/www.whitehouse.gov\/es\/administracion\/presidente-biden\/\" target=\"_blank\" rel=\"noreferrer noopener\">Joe Biden<\/a> conllev\u00f3 un reajuste casi de 180 grados de la pol\u00edtica exterior. La prueba se est\u00e1 viendo estos d\u00edas en Washington, donde los norteamericanos se han vestido de gala y empleado a fondo para recibir hasta a 40 jefes de Estado africanos y, como acertadamente titulaba este pasado mi\u00e9rcoles el peri\u00f3dico <a href=\"https:\/\/elpais.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">El Pa\u00eds<\/a>, \u2018cortejar\u2019 a \u00c1frica para que los Estados Unidos vuelvan a ser un socio fundamental y recuperen ese prestigio que ten\u00edan como socio prioritario con muchos de los pa\u00edses africanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos, obviamente, se dejan querer por Biden, sabedores de que en estos momentos son ellos los que tienen la mejor mano de cartas de toda la partida. Est\u00e1n en el centro del mapa, y pueden aliarse con quien quieran, con total libertad, para hacer negocios y procurar, cada uno a su manera, el desarrollo de sus pa\u00edses y, con ello, la mejor calidad de vida de sus ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las principales demandas africanas es plenamente geopol\u00edtica: la mayor, constante y asegurada presencia de \u00c1frica en los grandes \u00f3rganos de decisi\u00f3n internacional. Uno de ellos es el <a href=\"https:\/\/es.wikipedia.org\/wiki\/G20\" target=\"_blank\" rel=\"noreferrer noopener\">G-20<\/a>, el del grupo de los pa\u00edses m\u00e1s ricos del mundo, a los que Biden ha dicho estar dispuesto a asegurar un asiento africano. Tambi\u00e9n para el <a href=\"https:\/\/www.un.org\/securitycouncil\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Consejo de Seguridad de Naciones Unidas<\/a>, los africanos no quieren uno, sino dos puestos permanentes, sabiendo adem\u00e1s que muchos de los conflictos que ah\u00ed se dirimen se producen en su territorio y que el sistema vigente de reparto de esos puestos data de 1946, cuando a\u00fan casi todo el continente estaba colonizado.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cidob.org\/biografias_lideres_politicos\/africa\/senegal\/macky_sall\" target=\"_blank\" rel=\"noreferrer noopener\">Macky Sall<\/a>, presidente de nuestra vecina Senegal y ahora presidente de turno de la <a href=\"https:\/\/casafrica.es\/es\/redes\/union-africana-ua\" target=\"_blank\" rel=\"noreferrer noopener\">Uni\u00f3n Africana<\/a>, se\u00f1alaba este martes en una entrevista con <a href=\"https:\/\/casafrica.es\/es\/redes\/new-york-times\" target=\"_blank\" rel=\"noreferrer noopener\">The New York Times<\/a> que, pese a la inmensidad del continente, pese a sus 1400 millones de habitantes y su PIB conjunto de 2700 millones de d\u00f3lares, \u201c\u00c1frica sigue estando en la periferia\u201d. \u201cA la hora de decidir el destino del mundo, debe haber m\u00e1s espacio para \u00c1frica\u201d, a\u00f1ad\u00eda.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al continente africano, adem\u00e1s, la cumbre le llega en un momento clave, en una encrucijada. Por un lado, el apremio al que someten varios factores negativos. El Cuerno de \u00c1frica (en especial, Somalia) y el Sahel viven una terrible hambruna de la que les he hablado insistentemente en anteriores art\u00edculos, en la que los efectos de la emergencia clim\u00e1tica (cuatro a\u00f1os seguidos de estaciones de lluvias sin lluvias) se suceden con terribles, cortas y da\u00f1inas inundaciones que erosionan el poco suelo f\u00e9rtil que queda en zonas con calores extremos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la emergencia alimentaria se le suma el componente securitario, del que los norteamericanos est\u00e1n muy pendientes por el auge del yihadismo en puntos como el Sahel, el norte de Nigeria o Somalia, y que amenaza con extenderse hacia los pa\u00edses costeros de \u00c1frica Occidental. El descontento social (agravado por terribles datos de inflaci\u00f3n a causa del encarecimiento de materias primas) y el hambre son, a la postre, el mejor de los reclutadores para estos yihadistas, que, como nos ha contado en ocasiones la periodista <a href=\"https:\/\/casafrica.es\/es\/persona\/beatriz-mesa\" target=\"_blank\" rel=\"noreferrer noopener\">Beatriz Mesa<\/a>, son primero bandidos y narcotraficantes antes que fundamentalistas religiosos. Es decir, que el dinero es lo que les mueve.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el lado positivo de esta encrucijada, empiezan a aflorar las primeras noticias positivas alrededor de la puesta en marcha de la <a href=\"https:\/\/au-afcfta.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zona de Libre Comercio Africana<\/a>, la AfCFTA (por sus siglas en ingl\u00e9s), la que se convertir\u00e1 en la zona comercial m\u00e1s grande del planeta y que tiene como gran objetivo incrementar el comercio intraafricano. Si ahora en Europa el 67 % de lo que se produce acaba en alg\u00fan pa\u00eds europeo, el 60 % de lo que se produce en Asia acaba en pa\u00edses asi\u00e1ticos, o el 46 % de lo que se produce en el continente americano acaba en alg\u00fan pa\u00eds americano, en \u00c1frica ese dato es solo del 15 %. Y esa cifra sigue situando al continente, como lamenta el presidente senegal\u00e9s, en la periferia.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya hay, por ejemplo, empresas keniatas llevando a Ghana bater\u00edas de veh\u00edculos con el sello \u2018made in Kenia\u2019 (la condici\u00f3n esencial para entrar en la rebaja de aranceles de la nueva zona comercial es que se pueda acreditar que son productos africanos). Poco a poco, pues, empezaremos a ver casos de productos africanos movi\u00e9ndose libremente (esto a\u00fan con comillas, porque lo que hay inicialmente es una reducci\u00f3n progresiva de los aranceles), algo que tiene que ir aparejado con una mejora de las facilidades log\u00edsticas (y por lo tanto de las infraestructuras, tanto de carreteras y puertos como, muy importante, energ\u00e9ticas). En estos avances, sin duda, Estados Unidos deber\u00eda tambi\u00e9n ir jugando un papel cada vez m\u00e1s relevante, y sobre todo respetar el hecho de que, pese a los acuerdos de comercio que ya existan con el continente (el llamado acuerdo <a href=\"https:\/\/www.brookings.edu\/wp-content\/uploads\/2016\/06\/agoa_full_report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">AGOA<\/a>, nacido en el mandato de <a href=\"https:\/\/www.cidob.org\/biografias_lideres_politicos\/america_del_norte\/estados_unidos\/bill_clinton\" target=\"_blank\" rel=\"noreferrer noopener\">Bill Clinton<\/a>), los africanos procuran incrementar su comercio intraafricano, y eso debe ser apoyado y fortalecido por los norteamericanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque una de las principales moralejas que nos deja este an\u00e1lisis del panorama geopol\u00edtico africano es que la antigua relaci\u00f3n entre partes ha cambiado completamente. Ahora no se trata de decirle a los africanos \u2018vamos a ayudarles con esto, esto y esto\u2019. Lo que ocurre ahora, y en cierta manera los africanos lo han aprendido y practicado a base de tratar con chinos, rusos, turcos y hasta brasile\u00f1os, es que las conversaciones deben empezar de otra manera: \u00bfC\u00f3mo podemos ayudarles? \u00bfC\u00f3mo podemos serles \u00fatiles para su desarrollo? Y ese ejercicio de humildad, de tratar realmente de igual a tu contraparte, ser\u00e1 muy interesante comprobar si es algo que pondr\u00e1n en pr\u00e1ctica los norteamericanos en el continente africano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/casafrica.es\/es\/persona\/jose-segura-clavell\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Segura Clavell<\/a>, director general de <a href=\"https:\/\/casafrica.es\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Casa \u00c1frica<\/a>, y publicado el 16 de diciembre de 2022 en <a href=\"https:\/\/www.eldiario.es\/canariasahora\/canarias-opina\/africa-dialoga-biden_132_9799704.html\" target=\"_blank\" rel=\"noreferrer noopener\">eldiario.es<\/a> y en <a href=\"https:\/\/kioscoinsular.com\/portada\/africa-dialoga-con-biden\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kiosco Insular<\/a> y el 17 de diciembre en <a href=\"https:\/\/www.canarias7.es\/internacional\/africa-dialoga-biden-20221217141114-nt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Canarias7<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos celebra su gran cumbre con los pa\u00edses africanos con grandes anuncios de inversiones y compromisos de apoyar el mayor peso internacional de un continente que en los \u00faltimos a\u00f1os se ha sentido m\u00e1s apoyado por parte de chinos y rusos El mandato del anterior presidente norteamericano, Donald Trump, supuso para las relaciones entre [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[500,525,541,664,738,768,2545,1054,2719,1777,2381,1805,1880,1882],"class_list":["post-17354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-geopolitica","tag-comercio","tag-conflictos","tag-cooperacion","tag-destacado","tag-economia2","tag-ejercito","tag-empresas","tag-hambruna","tag-negocios","tag-pib","tag-politica-3","tag-politica-exterior","tag-recomendamos","tag-recursos-naturales"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts\/17354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/comments?post=17354"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts\/17354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/media\/17356"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/media?parent=17354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/categories?post=17354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/tags?post=17354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}