{"id":34657,"date":"2025-12-18T11:26:34","date_gmt":"2025-12-18T10:26:34","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=34657"},"modified":"2025-12-18T11:26:39","modified_gmt":"2025-12-18T10:26:39","slug":"fura-la-bebida-tradicional-que-nutre-a-un-pais","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/en\/economia-desarrollo\/fura-la-bebida-tradicional-que-nutre-a-un-pais\/","title":{"rendered":"Fura, la bebida tradicional que nutre a un pa\u00eds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ma\u00efmouna Diora es una mujer l\u00edder en N\u00edger. La empresaria y presidenta de la Asociaci\u00f3n Nigerina de Federaciones Interprofesionales de leche, una entidad que agrupa a las asociaciones de ganaderos y productores e industrias lecheras con el fin de desarrollar la industria local de l\u00e1cteos, es un ejemplo para miles de mujeres de este pa\u00eds del Sahel. En un pa\u00eds donde el sector ganadero y lechero est\u00e1 dirigido mayoritariamente por hombres, ser la l\u00edder de tal confederaci\u00f3n demuestra la inteligencia y el liderazgo de esta mujer apasionada con contribuir al desarrollo sostenible de su pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta estudi\u00f3 agroqu\u00edmica aplicada a la alimentaci\u00f3n y a la salud en Marruecos. Tras acabar sus estudios, volvi\u00f3 a N\u00edger. \u201cHab\u00eda un banco que daba fondos a j\u00f3venes graduados que terminaban sus estudios, as\u00ed que aprovech\u00e9 la oportunidad, ped\u00ed un pr\u00e9stamo y cre\u00e9 \u201cLa lecher\u00eda del Sahel\u201d porque quer\u00eda transformar la leche local para hacer buenos yogures como los que ten\u00eda en Marruecos\u201d. La empresaria fund\u00f3, hace ya m\u00e1s de 20 a\u00f1os, la primera empresa de l\u00e1cteos en N\u00edger que consigui\u00f3 producir y comercializar a gran escala una bebida tradicional de esta regi\u00f3n africana, el fura, uno de los m\u00faltiples productos que la etnia peul cocina a base de leche. Adem\u00e1s de esta bebida tradicional peul, tambi\u00e9n elaboran yogures enriquecidos con minerales y vitaminas a precios asequibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fura, que en la lengua local hausa significa &#8220;bola de mijo&#8221;, era realizada por las mujeres, principalmente n\u00f3madas, que pose\u00edan ganado. Tras fermentar la leche en calabazas, la mezclaban con las bolas de mijo ya cocinadas. Esta bebida tan nutritiva por sus carbohidratos, fibra, calcio y prote\u00ednas ha sido siempre un elemento esencial para las poblaciones de pastores n\u00f3madas del Sahel. Debido a que una vez mezclado el cereal con la leche fermentada perec\u00eda r\u00e1pidamente, su ingesta estaba limitada a las poblaciones que criaban ganado, ya que apenas se comercializaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta bebida tradicional es consumida en zonas rurales de diversos pa\u00edses del Sahel donde hay pastores peul, como Burkina Faso, Mauritania o Mali, pero con la comercializaci\u00f3n en supermercados y la venta en botellas y envases de pl\u00e1stico han conseguido que su consumo se expanda tambi\u00e9n a la poblaci\u00f3n urbana y sedentaria. En un pa\u00eds como N\u00edger, donde seg\u00fan el <a href=\"https:\/\/www.casafrica.es\/es\/redes\/programa-mundial-de-alimentos-0\" data-type=\"link\" data-id=\"https:\/\/www.casafrica.es\/es\/redes\/programa-mundial-de-alimentos-0\" target=\"_blank\" rel=\"noreferrer noopener\">Programa Mundial de Alimentos<\/a> de <a href=\"https:\/\/www.un.org\/es\/\" data-type=\"link\" data-id=\"https:\/\/www.un.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Naciones Unidas<\/a> la malnutrici\u00f3n cr\u00f3nica en los ni\u00f1os de 6 a 59 meses es del 47 % y m\u00e1s de un mill\u00f3n y medio de ni\u00f1os sufren malnutrici\u00f3n moderada, poder comercializar l\u00e1cteos a gran escala en un territorio tan amplio ha favorecido la mejora de la alimentaci\u00f3n de miles de familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando fui a estudiar a Marruecos, vi que el yogur estaba en los pueblos, estaba en todas partes, cualquiera pod\u00eda comprarlo y era barato. Era muy bueno, ten\u00eda un buen sabor por la leche local. Cada vez que lo compraba, dec\u00eda: tan pronto como tenga la oportunidad, har\u00e9 lo mismo en N\u00edger\u201d. Y as\u00ed lo hizo. En 2006 cre\u00f3 su propia empresa de l\u00e1cteos en Niamey. En esta \u00e9poca, el comercio de yogures en N\u00edger era minoritario. \u201cHab\u00eda una necesidad en el pa\u00eds. El consumo de yogur era un lujo, era para la gente que ten\u00eda dinero en las grandes ciudades, poca gente lo conoc\u00eda\u201d, afirma la empresaria. \u201cAl mismo tiempo, sab\u00eda que hab\u00eda mucha malnutrici\u00f3n y que ten\u00edamos leche local, por lo que pod\u00edamos mejorar la nutrici\u00f3n en N\u00edger\u201d. El yogur y el fura, al ser casi l\u00edquidos, pueden ser consumidos por ni\u00f1os peque\u00f1os, quienes tienen los mayores d\u00e9ficits nutricionales, junto con las mujeres embarazadas, en el Sahel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La malnutrici\u00f3n hace que el retraso en el crecimiento infantil en los ni\u00f1os y ni\u00f1as nigerinos menores de 5 a\u00f1os fuese de un 46,7 %, seg\u00fan la <a href=\"https:\/\/humanidades.com\/organizacion-mundial-de-la-salud-oms\/\" data-type=\"link\" data-id=\"https:\/\/humanidades.com\/organizacion-mundial-de-la-salud-oms\/\" target=\"_blank\" rel=\"noreferrer noopener\">Organizaci\u00f3n Mundial de la Salud<\/a> en 2020. Este retraso en el crecimiento tiene graves consecuencias para la salud del infante y puede desencadenar problemas cognitivos. Esta patolog\u00eda se debe principalmente a la escasa diversificaci\u00f3n en la dieta y la falta de acceso a los alimentos en los hogares m\u00e1s pobres. Por eso, la leche es m\u00e1s que una simple bebida en N\u00edger. De hecho, es un alimento de base que contribuye significativamente a la seguridad alimentaria y, a la vez, tiene un valor sociocultural. Adem\u00e1s, est\u00e1 asociado a la identidad peul, tiene un valor religioso y curativo, es s\u00edmbolo de abundancia y est\u00e1 presente en todas las comidas de esta etnia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La producci\u00f3n se hace en la f\u00e1brica en Niamey, pero venden en localidades muy alejadas de la capital. \u201cEn Agadez y Zinder, por el momento, tenemos clientes a los que les enviamos los productos en autobuses. Hacen los pedidos, los ponemos en neveras (port\u00e1tiles) y los enviamos a Agadez, Maradi, Rosso\u201d. A las grandes ciudades que est\u00e1n cerca de la capital, un d\u00eda a la semana un cami\u00f3n lleva los productos l\u00e1cteos. pero a las poblaciones m\u00e1s lejanas solo les env\u00edan si alguien hace un pedido. El 80 % de la poblaci\u00f3n nigerina vive en zonas rurales, lo que dificulta el acceso a la electricidad, pero tambi\u00e9n a alimentos fortificados que se producen en las grandes ciudades por los problemas en el transporte en un pa\u00eds con una superficie casi 2,5 veces mayor que la de Espa\u00f1a y con escasas redes de transporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa leche es un producto perecedero que se echa a perder r\u00e1pidamente, as\u00ed que necesitamos camiones refrigerados, lugares para mantener la cadena de fr\u00edo. Ahora mismo no podemos permitirnos comprar un cami\u00f3n refrigerado\u201d, explica la presidenta de ANFILAIT. Seg\u00fan un informe del <a href=\"https:\/\/www.casafrica.es\/es\/redes\/banco-mundial\" data-type=\"link\" data-id=\"https:\/\/www.casafrica.es\/es\/redes\/banco-mundial\" target=\"_blank\" rel=\"noreferrer noopener\">Banco Mundial<\/a> en 2021, solo el 18 % de la poblaci\u00f3n ten\u00eda acceso a la electricidad, por lo que los productos perecederos como los l\u00e1cteos han de ser consumidos cuando se compran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que la ganader\u00eda ocup\u00f3, de acuerdo al Banco Mundial, el 15 % del PIB en 2022, la producci\u00f3n de leche no era suficiente para abastecer toda la demanda del pa\u00eds, por lo que ten\u00edan que importarla. La leche importada en polvo es consumida masivamente porque el coste es menor que la leche l\u00edquida y no tiene problemas de perenci\u00f3n como la leche fresca. Las grandes multinacionales producen en masa esta leche en polvo y consiguen venderla en N\u00edger a un coste menor, lo cual perjudica al sector lechero local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa de Ma\u00efmouna utiliza leche fresca de vaca para elaborar sus productos. Aunque sopes\u00f3 usar leche de camella, la cual es muy consumida en el Sahel, al no haber suficientes productores que pudieran abastecerle la gran cantidad de leche que necesitaba para elaborar los diferentes productos l\u00e1cteos decidi\u00f3 decantarse por buscar a productores de b\u00f3vidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dureza del clima y las dificultades de cultivar en este pa\u00eds por sus tierras \u00e1ridas hacen que no se pueda cultivar en una gran parte del pa\u00eds, lo que encarece los precios de los alimentos. El golpe de Estado de 2023, las sanciones de la <a href=\"https:\/\/www.casafrica.es\/es\/redes\/comunidad-economica-de-estados-de-africa-occidental-cedeao\" data-type=\"link\" data-id=\"https:\/\/www.casafrica.es\/es\/redes\/comunidad-economica-de-estados-de-africa-occidental-cedeao\" target=\"_blank\" rel=\"noreferrer noopener\">CEDEAO<\/a>, as\u00ed como el terrorismo que azota el pa\u00eds y que ha generado el desplazamiento de medio mill\u00f3n de personas que huyen de la violencia, han generado que 2,2 millones de personas est\u00e9n en riesgo de inseguridad alimentaria en 2025. As\u00ed, esta empresa social que crea alimentos fortificados, producidos localmente, a precios asequibles con productos locales, ayuda a las mujeres embarazadas y lactantes y a ni\u00f1os a alimentarse mejor y contribuye al refuerzo de la econom\u00eda local. El sector privado tambi\u00e9n est\u00e1 jugando un rol en el desarrollo social de N\u00edger, lo cual es m\u00e1s necesario que nunca, ante la salida de una gran parte de las ONG del pa\u00eds tras el cambio de r\u00e9gimen en 2023 y los recortes en ayuda humanitaria de Estados Unidos y otros pa\u00edses occidentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo de <a href=\"https:\/\/www.casafrica.es\/es\/persona\/ana-lopez-garcia\" data-type=\"link\" data-id=\"https:\/\/www.casafrica.es\/es\/persona\/ana-lopez-garcia\" target=\"_blank\" rel=\"noreferrer noopener\">Ana L\u00f3pez Garc\u00eda<\/a>.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00efmouna Diora es una mujer l\u00edder en N\u00edger. La empresaria y presidenta de la Asociaci\u00f3n Nigerina de Federaciones Interprofesionales de leche, una entidad que agrupa a las asociaciones de ganaderos y productores e industrias lecheras con el fin de desarrollar la industria local de l\u00e1cteos, es un ejemplo para miles de mujeres de este pa\u00eds [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":35245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[170,3583,3586,500,3588,3467,3590,2521,3589,1880,1991],"class_list":["post-34657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-desarrollo","tag-alimentacion","tag-bebida","tag-bebida-tradicional","tag-comercio","tag-crecimiento-infantil","tag-economia2-en","tag-fabrica","tag-ganaderia","tag-malnutricion","tag-recomendamos","tag-seguridad-alimentaria"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts\/34657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/comments?post=34657"}],"version-history":[{"count":2,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts\/34657\/revisions"}],"predecessor-version":[{"id":35244,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/posts\/34657\/revisions\/35244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/media\/35245"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/media?parent=34657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/categories?post=34657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/en\/wp-json\/wp\/v2\/tags?post=34657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}