{"id":16603,"date":"2022-06-27T11:56:28","date_gmt":"2022-06-27T10:56:28","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=16603"},"modified":"2022-06-27T13:36:07","modified_gmt":"2022-06-27T12:36:07","slug":"las-tres-fronteras-la-zona-cero-de-la-yihad-en-el-sahel","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/politica-geopolitica\/las-tres-fronteras-la-zona-cero-de-la-yihad-en-el-sahel\/","title":{"rendered":"Las Tres Fronteras (la \u2018zona cero\u2019 de la yihad en el Sahel)"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Con la nueva exposici\u00f3n de Casa \u00c1frica queremos seguir poniendo el foco en esta regi\u00f3n, cada vez m\u00e1s insegura e inestable, porque de su tratamiento informativo en todo el mundo depender\u00e1 la necesaria respuesta que articule la comunidad internacional<\/em>.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este pasado mi\u00e9rcoles hemos inaugurado en <a href=\"https:\/\/casafrica.es\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Casa \u00c1frica<\/a> una <a href=\"https:\/\/www.casafrica.es\/es\/evento\/las-tres-fronteras\" target=\"_blank\" rel=\"noreferrer noopener\">exposici\u00f3n<\/a> que muestra el trabajo conjunto que el periodista canario <a href=\"https:\/\/casafrica.es\/es\/persona\/jose-naranjo\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Naranjo<\/a> y el fot\u00f3grafo andaluz <a href=\"https:\/\/www.juanluisrod.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Juan Luis Rod<\/a> han hecho por el Sahel, concretamente en la llamada zona de las Tres Fronteras, el gran espacio donde convergen las l\u00edneas fronterizas de Mali, N\u00edger y Burkina Faso y que en estos momentos constituye el coraz\u00f3n, o la \u2018zona cero\u2019, del yihadismo en la regi\u00f3n del Sahel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es en esta zona donde mayor n\u00famero de ataques, fallecidos y, consecuentemente, de desplazados se han producido en los \u00faltimos a\u00f1os, y que sin duda ha contribuido enormemente a la crisis pol\u00edtica que viven los pa\u00edses sahelianos: Mali o Burkina Faso, por ejemplo, han sufrido golpes de Estado y ahora viven bajo juntas militares, que en su momento justificaron el derrocamiento del poder pol\u00edtico democr\u00e1tico en la incapacidad de los pol\u00edticos para contener la expansi\u00f3n y amenaza yihadista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conflicto del Sahel, recordemos, suma ya 25 000 muertes en los \u00faltimos diez a\u00f1os, pero a diferencia de, por ejemplo, la guerra de Ucrania en este conflicto africano no hay im\u00e1genes, no hay v\u00eddeos que muestren la crudeza de la guerra, no hay fotos ni de las v\u00edctimas despu\u00e9s de los ataques. Ocurre todo en una regi\u00f3n enorme (solo la frontera entre N\u00edger y Burkina Faso mide m\u00e1s de 800 kil\u00f3metros), as\u00ed que estamos hablando de zonas muy poco accesibles, inseguras, sin presencia del ej\u00e9rcito ni de la polic\u00eda y con unas fronteras absolutamente porosas, que permiten a los yihadistas atacar en un pa\u00eds y esconderse en otro (lo hacen usando motocicletas, terriblemente efectivas para este tipo de terreno), refugi\u00e1ndose en enormes zonas boscosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El momento temporal en que abrimos esta exposici\u00f3n, para que la ciudadan\u00eda entienda la importancia de lo que sucede en el Sahel, no puede ser, lamentablemente, m\u00e1s oportuno. El d\u00eda en que present\u00e1bamos la muestra a los medios, desayun\u00e1bamos leyendo que un ataque de una de las organizaciones vinculadas a Al Qaeda en la zona, la llamada \u2018katiba Macina\u2019, hab\u00eda asesinado a un total de 132 personas, civiles, en Mali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este pa\u00eds, adem\u00e1s, la junta militar surgida de un golpe de Estado hace ya casi dos a\u00f1os, ha llevado al extremo su enemistad con Francia, que impulsaba la respuesta militar a los yihadistas y ha logrado que los franceses se retiren del pa\u00eds, dejando paso a Rusia, que tiene, supuestamente ayudando al Gobierno, al grupo de mercenarios Wagner, no precisamente conocidos por su respeto a los derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La complejidad del entorno, pues, es enorme. Y uno de los grandes problemas de este conflicto (el primero y m\u00e1s grande, obviamente, es siempre el impacto que tiene en la poblaci\u00f3n) es que su visibilidad internacional es escasa y su presencia medi\u00e1tica, lamentablemente, casi nula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sahel, dec\u00eda Jos\u00e9 Naranjo, \u201cdebe abandonar la periferia informativa y ocupar una posici\u00f3n central\u201d en la preocupaci\u00f3n que a diario se muestra hacia los temas internacionales. Esa posici\u00f3n central permitir\u00eda empezar a copar portadas, minutos de televisi\u00f3n, las conversaciones de la gente y coadyuvar\u00eda, entiendo, a que toda esa inercia fuerce movimientos, decisiones y gestos de la comunidad internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les quiero recomendar desde este art\u00edculo de forma encarecida que se acerquen a Casa \u00c1frica, que se queden impresionados por la calidad de las 65 im\u00e1genes de Juan Luis Rod, y que despu\u00e9s la recomienden a sus amigos y conocidos. En vinilo, en la pared, hay una contundente frase del secretario general de Naciones Unidas, <a href=\"https:\/\/www.un.org\/sg\/es\/content\/sg\/biography\" target=\"_blank\" rel=\"noreferrer noopener\">Antonio Guterres<\/a>, que debe quedarnos grabada a fuego: \u201cla crisis del Sahel ya no es solo una cuesti\u00f3n regional o africana, sino una amenaza global\u201d. Tanto el comisario europeo <a href=\"https:\/\/ec.europa.eu\/commission\/commissioners\/2019-2024\/borrell-fontelles_es\" target=\"_blank\" rel=\"noreferrer noopener\">Josep Borrell<\/a> como nuestro ministro de Exteriores, <a href=\"https:\/\/www.casafrica.es\/es\/persona\/jose-manuel-albares-bueno\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Manuel Albares<\/a>, han afirmado que la seguridad en Europa depende de la seguridad de esta regi\u00f3n. Y en ese sentido, reitero, el escenario securitario en los pa\u00edses sahelianos pinta cada vez peor. La inminente cumbre de la <a href=\"https:\/\/www.nato.int\/nato-welcome\/index_es.html\" target=\"_blank\" rel=\"noreferrer noopener\">OTAN<\/a> en Madrid debe ser, aunque todos los ojos est\u00e9n mirando hacia Ucrania, un primer escenario para llamar la atenci\u00f3n sobre el Sahel e impulsar un compromiso, al menos, de exhaustivo seguimiento de la situaci\u00f3n y compromiso de apoyo internacional en b\u00fasqueda de la paz y seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seguridad es uno de los factores diversos (hay m\u00e1s, como la hambruna, la crisis clim\u00e1tica o los efectos de la a\u00fan no superada crisis econ\u00f3mica de la pandemia) que impulsan adem\u00e1s las migraciones desde el continente africano hacia nuestras islas, primero, pero en esencia hacia todo el continente europeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo peri\u00f3dico <a href=\"https:\/\/elpais.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">El Pa\u00eds<\/a> utilizaba el pasado mi\u00e9rcoles un titular contundente al respecto: \u201cBruselas teme que la guerra de Putin provoque oleadas migratorias hacia la UE desde el norte de \u00c1frica\u201d. Pese al matiz que debe hac\u00e9rsele al titular, de que la guerra de Putin en Ucrania solo ha actuado como acelerador de tendencias que ya ve\u00edamos (ha agravado las hambrunas y encarecido las materias primas que ya empezaban a escasear antes del conflicto), el principal rechazo que me ha generado esta informaci\u00f3n es que seguimos tirando de la narrativa del miedo al enfocar el tema de la migraci\u00f3n: usar el t\u00e9rmino \u2018oleadas migratorias\u2019 demuestra que tantos a\u00f1os despu\u00e9s de recibir pateras y cayucos, y tantas informaciones despu\u00e9s que han tratado de mostrarnos la complejidad del fen\u00f3meno, seguimos leyendo titulares simplistas que tratan de \u2018oleadas\u2019 a seres humanos cuya valent\u00eda deber\u00eda ser puesta en un pedestal: buscan la manera de ganarse la vida y una alternativa para, desde otro lugar, ayudar a los que han dejado atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi convencimiento es que, ante la narrativa de las \u2018oleadas\u2019 o las \u2018avalanchas\u2019 de africanos, debemos seguir apostando por la sensibilizaci\u00f3n para poder empatizar con esas personas, conociendo su vida, sus historias y anhelos. Su camino, en definitiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y para muestra, un bot\u00f3n. Este pasado martes asist\u00ed en la nueva <a href=\"https:\/\/www.laspalmasgc.es\/es\/areas-tematicas\/cultura\/bibliotecas\/biblioteca-publica-municipal-josefina-de-la-torre\/\" target=\"_blank\" rel=\"noreferrer noopener\">Biblioteca Josefina de la Torre<\/a>, frente a la Playa de Las Canteras, a la <a href=\"https:\/\/www.casafrica.es\/es\/evento\/presentacion-del-libro-una-luz-en-el-desierto\" target=\"_blank\" rel=\"noreferrer noopener\">presentaci\u00f3n<\/a> de uno de los libros de la colecci\u00f3n Casa \u00c1frica, titulado \u2018<a href=\"https:\/\/www.casafrica.es\/es\/publicaciones\/una-luz-en-el-desierto\" target=\"_blank\" rel=\"noreferrer noopener\">Una luz en el desierto<\/a>\u2019 (<a href=\"https:\/\/bailedelsol.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Editorial Baile del Sol<\/a>). Un libro coescrito entre el periodista bilba\u00edno <a href=\"https:\/\/www.casafrica.es\/es\/persona\/pascual-perea\" target=\"_blank\" rel=\"noreferrer noopener\">Pascual Perea<\/a> y el m\u00fasico camerun\u00e9s <a href=\"https:\/\/www.casafrica.es\/es\/persona\/isaac-ebelle\" target=\"_blank\" rel=\"noreferrer noopener\">Isaac Ebelle<\/a> que cuenta la historia de este \u00faltimo en su largo y dif\u00edcil trayecto entre su pa\u00eds natal y nuestro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos habl\u00f3 de sus diversos intentos de llegar a Espa\u00f1a, de c\u00f3mo se dej\u00f3 la salud y casi la vida, de c\u00f3mo se siente una persona que en innumerables momentos del periplo es tratada peor que los animales, atada, maltratada y robada. Nos contaba c\u00f3mo, a\u00f1os despu\u00e9s de llegar a Espa\u00f1a y dedicando ahora parte de su vida a la sensibilizaci\u00f3n de j\u00f3venes espa\u00f1oles y africanos, la tristeza sigue apoder\u00e1ndose de \u00e9l cada vez que sabe de la noticia, como ocurri\u00f3 la semana pasada, de un joven africano que falleci\u00f3 intentando cruzar a nado el r\u00edo Bidasoa para tratar de atravesar la frontera entre Espa\u00f1a y Francia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O incluso contaba c\u00f3mo a\u00f1os despu\u00e9s de haber llegado a este pa\u00eds sigue ocurri\u00e9ndole que en la guagua (el autob\u00fas en Bilbao) hay gente que prefiere estar de pie que sentarse al lado del negro. Y todos los que est\u00e1bamos ah\u00ed pensamos que eso no ocurre aqu\u00ed, en Canarias, en 2022, pero otros africanos asistentes a la presentaci\u00f3n nos dijeron que s\u00ed, que ese a\u00fan es su d\u00eda a d\u00eda. Cu\u00e1nto tenemos a\u00fan que aprender, cu\u00e1nto tenemos a\u00fan que empatizar, para por fin superar esos prejuicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/casafrica.es\/es\/persona\/jose-segura-clavell\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Segura Clavell<\/a>, director general de Casa \u00c1frica, y publicado en <a href=\"https:\/\/kioscoinsular.com\/portada\/las-tres-fronteras-la-zona-cero-de-la-yihad-en-el-sahel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kiosco Insular<\/a> el 25 de junio de 2022 y en <a href=\"https:\/\/www.canarias7.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Canarias7<\/a> el 26 de junio de 2022.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la nueva exposici\u00f3n de Casa \u00c1frica queremos seguir poniendo el foco en esta regi\u00f3n, cada vez m\u00e1s insegura e inestable, porque de su tratamiento informativo en todo el mundo depender\u00e1 la necesaria respuesta que articule la comunidad internacional. Este pasado mi\u00e9rcoles hemos inaugurado en Casa \u00c1frica una exposici\u00f3n que muestra el trabajo conjunto que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":16604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[526,575,595,644,2596,664,768,872,955,1025,1027,1041,1490,2381,1852,1880,1962,1990,2117],"class_list":["post-16603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-geopolitica","tag-conflictos-armados","tag-crisis","tag-cultura","tag-derechos-humanos","tag-desplazamientos","tag-destacado","tag-ejercito","tag-exposicion","tag-fotografia","tag-gobierno","tag-golpe-de-estado","tag-guerra","tag-migracion","tag-politica-3","tag-racismo","tag-recomendamos","tag-sahel","tag-seguridad","tag-terrorismo"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/16603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=16603"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/16603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/16604"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=16603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=16603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=16603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}