{"id":17652,"date":"2023-05-11T09:12:32","date_gmt":"2023-05-11T08:12:32","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=17652"},"modified":"2025-09-18T10:46:48","modified_gmt":"2025-09-18T09:46:48","slug":"egipto-esta-en-venta","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/economia-desarrollo\/egipto-esta-en-venta\/","title":{"rendered":"<strong>Egipto est\u00e1 en venta<\/strong>"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em>\u201cO morimos de hambre o nos defendemos\u201d<\/em>, Hamdy Hossin, obrero y sindicalista egipcio.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>La parte m\u00e1s importante de la f\u00e1brica es la que compra el algod\u00f3n<\/strong>\u201d, dice Ibrahim Salem Mohamedin, antiguo encargado de Misr Helwan, una las empresas m\u00e1s importantes de la historia de Egipto. \u201cCompr\u00e1bamos una cuarta parte de la producci\u00f3n de algod\u00f3n de Egipto y lo hil\u00e1bamos aqu\u00ed en la f\u00e1brica\u201d, a\u00f1ade. El documental <a href=\"https:\/\/www.aljazeera.com\/program\/revolution-through-arab-eyes\/2012\/2\/22\/the-factory\">\u201cThe factory\u201d,<\/a> publicado en 2012, muestra la trayectoria de esta planta textil que lleg\u00f3 a representar el 20% de las exportaciones egipcias al mundo: sus toallas, su ropa o sus uniformes sirvieron tanto para conseguir divisas como para vestir al ej\u00e9rcito egipcio. Sus vaivenes reflejan la historia moderna del pa\u00eds norteafricano, desde la lucha por la independencia hasta las reformas liberales de los 80, pasando por el socialismo sin socialistas de Nasser. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un momento del documental, Mohamedin dice una frase lapidaria: \u201cEn 1974 empez\u00f3 el liberalismo econ\u00f3mico. Consum\u00edamos m\u00e1s de lo que produc\u00edamos. Fue un gran error\u201d. Egipto, que fue absorbido por el imperio brit\u00e1nico en 1882 por un impago de deuda tras la ca\u00edda de los precios del algod\u00f3n, se encuentra de nuevo en la encrucijada. Una d\u00e9cada despu\u00e9s de la revoluci\u00f3n que tumb\u00f3 a Hosni Mubarak, el pa\u00eds se est\u00e1 vendiendo, casi literalmente, a trozos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEn 1974 empez\u00f3 el liberalismo econ\u00f3mico. Consum\u00edamos m\u00e1s de lo que produc\u00edamos. Fue un gran error\u201d<\/p>\n<cite>Ibrahim Salem Mohamedin<\/cite><\/blockquote>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.esafrica.es\/en\/desarrollo\/el-dilema-del-presidente-egipcio\/\">Tal y como reconoci\u00f3 el propio presidente egipcio, Abdel Fattah Al Sisi<\/a>, Egipto lleva muchos a\u00f1os gastando m\u00e1s de lo que ingresa y pidiendo prestado para tapar el agujero resultante. No es una cuesti\u00f3n de la manera de ser de los egipcios, es el funcionamiento de las finanzas internacionales: para que algunos pa\u00edses tengan super\u00e1vits comerciales -m\u00e1s ventas al exterior que compras- otros deben tener d\u00e9ficits. No todos pueden tener super\u00e1vits a la vez, a no ser que fueran capaces de encontrar la demanda en alg\u00fan lugar extraterrestre. Los d\u00e9ficits de un pa\u00eds generan ganancias en otras latitudes. Entre los beneficiarios de las importaciones egipcias se hallan, por ejemplo, los fabricantes de armas de los pa\u00edses m\u00e1s ricos, que pueden contar con un cliente fiel en un pa\u00eds muy influido por su ej\u00e9rcito. O los vendedores de trigo, cruciales para garantizar que todos los egipcios puedan comer pan: el pa\u00eds produce 10 millones de toneladas anuales de trigo, pero consume 20 millones. Todos los pa\u00edses buscan el equilibrio entre satisfacer las necesidades del interior y adaptarse a las demandas del exterior, y a veces se rompen unos cuantos platos por el camino. Hoy Egipto se halla en esta situaci\u00f3n: el a\u00f1o que viene tendr\u00e1 que pagar 20 000 millones de d\u00f3lares a sus acreedores -en 2012 pagaba poco menos de 3000 millones-, y deber\u00e1 racionar entre los pagos regulares de importaciones y sus obligaciones con los prestamistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La primera devaluaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El FMI requiri\u00f3 una reducci\u00f3n del valor de la moneda al estado egipcio en 2016. El gobierno de Al Sisi dej\u00f3 de intentar aguantar el valor de 8 libras por d\u00f3lar, y r\u00e1pidamente la divisa egipcia perdi\u00f3 la mitad de su valor hasta situarse en 16 libras por d\u00f3lar. Con la p\u00e9rdida de valor de la moneda se buscan dos efectos: el primero, que el pa\u00eds no gaste tantos d\u00f3lares -al ser estos m\u00e1s caros; el segundo, que sus productos sean m\u00e1s baratos en el exterior y consigan m\u00e1s compradores. Ambos buscan reducir el d\u00e9ficit comercial para que Egipto pueda exportar m\u00e1s de lo que importa. Otra consecuencia colateral es, tambi\u00e9n, el turismo: los visitantes de pa\u00edses que usen el d\u00f3lar o el euro, de repente, se convierten en una fuente de dinero vital para el pa\u00eds; y, para ellos, Egipto estar\u00e1 m\u00e1s barato que nunca. La jugada de 2016 es el equivalente a apretar el cintur\u00f3n de todos los trabajadores egipcios: sus sueldos valen mucho menos en d\u00f3lares, los productos importados que compren -como el pan hecho con trigo ucraniano- ser\u00e1n m\u00e1s caros, y sus ahorros -en caso de tenerlos- valdr\u00e1n m\u00e1s o menos la mitad de lo que val\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jugada es beneficiosa para el capital extranjero y la gente con informaci\u00f3n privilegiada. La clase alta, los funcionarios o los trabajadores de la ONU cambiar\u00e1n todas las libras egipcias de las que dispongan por d\u00f3lares americanos d\u00edas antes del anuncio de la devaluaci\u00f3n. Su acci\u00f3n contribuir\u00e1, a peque\u00f1a escala, al acaparamiento y la escasez de d\u00f3lares que, a su vez, hundir\u00e1 a\u00fan m\u00e1s la moneda local. El capital extranjero se encontrar\u00e1 con un pa\u00eds con salarios m\u00e1s bajos y productos m\u00e1s competitivos que vender en el exterior, o con un gobierno dispuesto a conseguir d\u00f3lares como sea. Por ejemplo, vendiendo bonos del estado a un 5% o un 6% de inter\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos movimientos se pueden ver, a gran escala, a trav\u00e9s de los acreedores de la deuda egipcia. En 2016 los prestamistas eran, en su mayor\u00eda, estados como Arabia Saud\u00ed, Emiratos \u00c1rabes Unidos, Kuwait, Alemania o el Banco Mundial. En 2021, solamente cinco a\u00f1os despu\u00e9s, la deuda se hab\u00eda duplicado y la mitad del stock se lo repart\u00edan entre prestamistas privados, el FMI y el Banco Mundial. Los estados hab\u00edan sido m\u00e1s prudentes desde 2016, pero los inversores privados se lanzaron a comprar <a href=\"https:\/\/www.esafrica.es\/en\/economia\/guia-para-entender-por-que-caen-los-paises\/\">deuda<\/a> egipcia: la cantidad en sus manos se multiplic\u00f3 por ocho. En 2019, cuando Egipto coloc\u00f3 algunos de sus bonos, ya se intu\u00eda que la devaluaci\u00f3n no hab\u00eda relanzado la econom\u00eda. La llegada del covid tumb\u00f3 la \u00faltima posibilidad de convertir en rentables algunas de las inversiones fara\u00f3nicas del estado egipcio: el turismo se desplom\u00f3 y Egipto se qued\u00f3 con las deudas de haber construido museos, hoteles e infraestructuras, pero sin los ingresos que hab\u00edan calculado que obtendr\u00edan con ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El futuro se juega en el Nilo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguir la historia del algod\u00f3n es seguir la historia de Egipto, pero es un elemento geogr\u00e1fico el que definir\u00e1 el futuro del pa\u00eds: el r\u00edo Nilo. De sus aguas dependen el algod\u00f3n -el 10% de las exportaciones del pa\u00eds son ropa y productos textiles- el trigo y el ma\u00edz. Durante d\u00e9cadas, la falta de acceso a los alimentos b\u00e1sicos se ha paliado con subsidios del gobierno para comprarlos. El FMI insiste en retirarlos por completo, pero el gobierno egipcio es consciente de que la revoluci\u00f3n de 2011 empez\u00f3, en parte, por el aumento de precios de la comida. Y mira de reojo como el r\u00e9gimen de Omar-al Bashir, en el vecino Sud\u00e1n, cay\u00f3 en 2019 por motivos similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La voluntad de Etiop\u00eda de poner en marcha <a href=\"https:\/\/elpais.com\/internacional\/2021-07-03\/el-pulso-por-el-agua-del-rio-nilo-agudiza-la-crisis-regional-entre-egipto-y-etiopia.html\">una presa en el Nilo<\/a> es la principal preocupaci\u00f3n egipcia. Este pa\u00eds del \u00c1frica oriental quiere aumentar su producci\u00f3n el\u00e9ctrica para impulsar su propia industria textil: un doble golpe para Egipto, que sumar\u00eda un competidor para su ropa y se quedar\u00eda sin parte del agua con la que riega sus cultivos. Si actualmente produce la mitad del trigo que necesita para alimentar a su poblaci\u00f3n, con menos agua necesitar\u00eda comprar a\u00fan m\u00e1s trigo en el exterior &#8211; y gastar m\u00e1s d\u00f3lares. Si la ropa et\u00edope es m\u00e1s barata que la de Egipto -el salario de un trabajador textil et\u00edope es de 40 d\u00f3lares, la mitad que un obrero egipcio-, Egipto podr\u00eda perder mercados donde vender su ropa -e ingresar\u00eda menos d\u00f3lares. La inflaci\u00f3n y los problemas que aquejan a los pa\u00edses afectados por la presa -Etiop\u00eda, Sud\u00e1n y Egipto- han aplazado temporalmente el debate, pero su resoluci\u00f3n definir\u00e1 las pr\u00f3ximas d\u00e9cadas de los 270 millones de personas que viven en los tres territorios. El \u00e1rbitro lo encontrar\u00e1n, seguramente, en alg\u00fan punto de Oriente Medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arabia Saud\u00ed, Emiratos \u00c1rabes y Qatar son ricos en petr\u00f3leo y gas, poseen fondos soberanos que controlan m\u00e1s de 2 billones de d\u00f3lares en activos -m\u00e1s que toda la econom\u00eda espa\u00f1ola, con un PIB de 1,4 billones- y tienen un problema com\u00fan: son secos y necesitan producir comida con la que alimentar a su poblaci\u00f3n. En los casos de Qatar y Emiratos, su superficie es, adem\u00e1s, muy peque\u00f1a. Su influencia en las zonas ba\u00f1adas por el Nilo es una necesidad: tienen mucho dinero, pero son pobres en agua; Sud\u00e1n, Egipto y Etiop\u00eda, en cambio, son m\u00e1s pobres pero tienen agua. Por ese motivo diferentes inversores de Oriente Medio han comprado terrenos en los tres pa\u00edses, y necesitan garantizar que les lleguen las exportaciones de trigo o ma\u00edz, pero tambi\u00e9n de tomates, naranjas, lechugas o cebollas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal y como explicaba en abril el corresponsal en Egipto Marc Espa\u00f1ol, \u201cen el documento que acompa\u00f1a al acuerdo de 3000 millones de d\u00f3lares que Egipto y el Fondo Monetario Internacional (FMI) firmaron en diciembre de 2022, El Cairo declar\u00f3 que hab\u00eda identificado un grupo de empresas estatales cuyas participaciones esperaba vender para recaudar 2500 millones de d\u00f3lares antes de junio.\u201d Los principales interesados en comprar esas empresas vienen de tres pa\u00edses: Emiratos \u00c1rabes, Arabia Saud\u00ed y Qatar. <a href=\"https:\/\/www.ft.com\/content\/6748465d-b1ca-4625-9d8f-b40620aa3f42\">Han inyectado el dinero con el que Egipto ha sobrevivido hasta hoy<\/a>, y ahora tienen prioridad a la hora de comprar las 32 empresas estatales a la venta. El proceso de privatizaci\u00f3n no ha arrancado como esperaban las autoridades egipcias: tras otra devaluaci\u00f3n -ya son necesarias 30 libras egipcias para conseguir un d\u00f3lar de Estados Unidos-, los inversores esperan que la moneda se estabilice. No quieren dar el paso demasiado pronto y ver como sus activos pierden valor a las pocas semanas. &nbsp;Con todo, el agujero financiero de Egipto es de 5000 millones de d\u00f3lares, seg\u00fan explicaba Espa\u00f1ol en su art\u00edculo en <a href=\"https:\/\/www.al-monitor.com\/originals\/2023\/04\/egypts-privatization-plans-stall-despite-growing-buzz#ixzz818Hs29UH\">\u2018The Monitor\u2019<\/a>. Ni siquiera vendiendo todo lo que esperaban las autoridades conseguir\u00edan la cantidad que necesitan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bancos, hoteles, mineras y petroleras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 del sector agr\u00edcola, las empresas a la venta abarcan todos los sectores de la econom\u00eda egipcia. La gran pregunta es qu\u00e9 pasar\u00e1 si Egipto completa su proceso de privatizaci\u00f3n. Algunas de estas empresas son propiedad del ej\u00e9rcito, el estamento m\u00e1s influyente de la vida pol\u00edtica egipcia: si se completaran las ventas, su peso en la econom\u00eda nacional disminuir\u00eda. En lo que respecta a los ciudadanos de a pie, cabe preguntarse qu\u00e9 pasar\u00e1 con ellos cuando los nuevos propietarios de esas empresas -algunas con un poder de mercado considerable- decidan recuperar su inversi\u00f3n subiendo los precios de los productos. Deber\u00e1n hacer frente a ese aumento del coste de la vida con salarios que ya han perdido pr\u00e1cticamente todo el poder adquisitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un momento de <em>\u2018The Factory\u2019<\/em>, uno de los trabajadores recuerda una de las frases m\u00e1s emblem\u00e1ticas de los huelguistas que protestaban contra la creciente desigualdad salarial en los 80: \u00ab\u00a0Ellos comen pollo: nosotros estamos hartos de comer jud\u00edas. Y las jud\u00edas ya est\u00e1n cansadas de nosotros\u00a0\u00bb. Hacia el final del documental aparece Nagy Haider, otro trabajador que se une a una protesta cuando nota como, meses despu\u00e9s de la ca\u00edda del r\u00e9gimen de Mubarak en 2011, el pueblo sigue viviendo mal: \u2018Cobro 550 libras egipcias. \u00bfQu\u00e9 puedo hacer con un salario tan bajo?\u2019, dice. Cuando pronunci\u00f3 esa frase, hace una d\u00e9cada, ese salario era el equivalente a unos 90 d\u00f3lares. Ahora son 18.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO morimos de hambre o nos defendemos\u201d, Hamdy Hossin, obrero y sindicalista egipcio. \u201cLa parte m\u00e1s importante de la f\u00e1brica es la que compra el algod\u00f3n\u201d, dice Ibrahim Salem Mohamedin, antiguo encargado de Misr Helwan, una las empresas m\u00e1s importantes de la historia de Egipto. \u201cCompr\u00e1bamos una cuarta parte de la producci\u00f3n de algod\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[648,664,2581,766,1802,1880],"class_list":["post-17652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-desarrollo","tag-desarrollo-economico","tag-destacado","tag-economia","tag-egipto","tag-politica","tag-recomendamos"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/17652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=17652"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/17652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/17653"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=17652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=17652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=17652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}