{"id":30358,"date":"2024-07-01T12:57:45","date_gmt":"2024-07-01T11:57:45","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=30358"},"modified":"2025-09-30T11:33:32","modified_gmt":"2025-09-30T10:33:32","slug":"las-ninas-suelen-leer-mejor-que-los-ninos-por-que-no-ocurre-lo-mismo-en-algunos-paises-africanos","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/cultura-y-educacion\/las-ninas-suelen-leer-mejor-que-los-ninos-por-que-no-ocurre-lo-mismo-en-algunos-paises-africanos\/","title":{"rendered":"Las ni\u00f1as suelen leer mejor que los ni\u00f1os: \u00bfpor qu\u00e9 no ocurre lo mismo en algunos pa\u00edses\u00a0africanos?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la\u00a0<a href=\"https:\/\/journals.plos.org\/plosone\/article?id=%2010.1371\/journal.pone.0057988\" target=\"_blank\" rel=\"noreferrer noopener\">mayor parte del planeta<\/a>,\u00a0<a href=\"https:\/\/www.oecd-ilibrary.org\/sites\/f56f8c26-en\/index.html?itemId=\/content\/component\/f56f8c26-en\" target=\"_blank\" rel=\"noreferrer noopener\">las ni\u00f1as superan a los ni\u00f1os en capacidad de lectura<\/a>. En comparaci\u00f3n con los ni\u00f1os, las ni\u00f1as tienen un mayor nivel de competencia lectora respecto al nivel esperado en cada curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este fen\u00f3meno se debe a\u00a0<a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/00131911003637006\" target=\"_blank\" rel=\"noreferrer noopener\">varias razones<\/a>. Por un lado, se ha comprobado que las ni\u00f1as poseen mayores aptitudes naturales, pero adem\u00e1s muestran mayor inter\u00e9s por la lectura que los ni\u00f1os. Ellas acostumbran a leer m\u00e1s y se les suele animar a que lean m\u00e1s que a los varones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a estos datos, los\u00a0<a href=\"https:\/\/link.springer.com\/article\/10.1007\/s11159-009-9148-x\" target=\"_blank\" rel=\"noreferrer noopener\">estudios realizados en \u00c1frica subsahariana<\/a>\u00a0revelan que la tendencia se ha invertido en algunos pa\u00edses de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La anomal\u00eda registrada en esta parte del continente africano hace pensar que las ni\u00f1as de estos pa\u00edses encuentran obst\u00e1culos que dificultan su escolarizaci\u00f3n y el desarrollo de su capacidad lectora. En mi calidad de dem\u00f3grafa social interesada en los resultados del aprendizaje en la regi\u00f3n, quise analizar m\u00e1s a fondo los datos y tratar de comprender cu\u00e1les podr\u00edan ser esos obst\u00e1culos. El\u00a0<a href=\"https:\/\/sdgs.un.org\/goals\/goal4\" target=\"_blank\" rel=\"noreferrer noopener\">Objetivo de Desarrollo Sostenible 4<\/a>, relativo a la equidad y la inclusi\u00f3n en la educaci\u00f3n, subraya la importancia de eliminar la brecha de g\u00e9nero en el aprendizaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un\u00a0<a href=\"https:\/\/www.tandfonline.com\/doi\/epdf\/10.1080\/18146627.2022.2151924?needAccess=true\" target=\"_blank\" rel=\"noreferrer noopener\">estudio reciente<\/a>, examin\u00e9 datos de 15 pa\u00edses africanos de las regiones meridional y oriental del continente \u2013entre ellos, Botsuana, Malaui, Kenia y Uganda\u2013 y descubr\u00ed que las estad\u00edsticas situaban a los ni\u00f1os por delante de las ni\u00f1as en seis de esos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, analic\u00e9 los posibles factores correlacionados con estas disparidades e identifiqu\u00e9 los siguientes: condiciones inadecuadas de higiene en la escuela, responsabilidades dom\u00e9sticas y de cuidado de otras personas a cargo de las ni\u00f1as y acoso en la escuela. Estos factores pueden conducir al absentismo o dificultar la capacidad de aprendizaje de las ni\u00f1as incluso estando escolarizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con tales datos podemos suponer que la mejora del saneamiento en el entorno escolar, la reducci\u00f3n de las tareas dom\u00e9sticas para las j\u00f3venes y la lucha contra el acoso podr\u00edan mejorar la competencia lectora de las ni\u00f1as en comparaci\u00f3n con la de los ni\u00f1os.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los datos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el estudio se examinaron los datos de 61\u00a0396 alumnas y alumnos de 5\u00ba de primaria (con una edad media de 13 a\u00f1os) de 15 pa\u00edses africanos. Los datos proced\u00edan de la\u00a0<a href=\"http:\/\/www.seacmeq.org\/?q=sacmeq-projects\/sacmeq-iii\" target=\"_blank\" rel=\"noreferrer noopener\">tercera evaluaci\u00f3n<\/a>\u00a0realizada por el Southern and Eastern Africa Consortium for Monitoring Educational Quality, que se llev\u00f3 a cabo entre 2009 y 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La evaluaci\u00f3n recogi\u00f3 informaci\u00f3n diversa sobre el entorno y los recursos escolares, las caracter\u00edsticas del profesorado y los antecedentes familiares del alumnado. Dicha informaci\u00f3n se obtuvo de la direcci\u00f3n de los centros, el profesorado de cada asignatura y el alumnado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 demostrado que las ni\u00f1as de \u00c1frica subsahariana se enfrentan a una serie de retos que afectan a su escolarizaci\u00f3n y a su evoluci\u00f3n en el colegio. Entre otros, las pr\u00e1cticas culturales que infravaloran la educaci\u00f3n femenina \u2013como el\u00a0<a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/13603110601183115\" target=\"_blank\" rel=\"noreferrer noopener\">matrimonio precoz<\/a>\u2013, un\u00a0<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0738059399000462\" target=\"_blank\" rel=\"noreferrer noopener\">menor apoyo acad\u00e9mico<\/a>\u00a0por parte de la familia y del profesorado que aquel que se ofrece a los ni\u00f1os y, por \u00faltimo, el\u00a0<a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/00220388.2012.671472\" target=\"_blank\" rel=\"noreferrer noopener\">acoso sexual<\/a>. La\u00a0<a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/j.1365-3156.2006.01600.x\" target=\"_blank\" rel=\"noreferrer noopener\">preocupaci\u00f3n por la seguridad y la higiene<\/a>\u00a0tambi\u00e9n influye, ya que los padres son m\u00e1s reacios a enviar a las ni\u00f1as al colegio si les preocupa que recorran largas distancias o que sufran acoso en la escuela. El\u00a0<a href=\"https:\/\/link.springer.com\/article\/10.1007\/s10640-015-9938-5\" target=\"_blank\" rel=\"noreferrer noopener\">peso de las tareas dom\u00e9sticas<\/a>\u00a0juega asimismo un papel importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi an\u00e1lisis muestra que algunos de estos factores pueden estar frenando el rendimiento de las ni\u00f1as en materia de lectura en los seis pa\u00edses donde los ni\u00f1os obtienen resultados significativamente superiores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lecciones por aprender<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No cabe duda de que los problemas identificados no son exclusivos de los seis pa\u00edses mencionados. Mis resultados indican adem\u00e1s que, incluso en aquellos pa\u00edses en los que el panorama es m\u00e1s igualitario y las ni\u00f1as obtienen mejores resultados que los ni\u00f1os, tales factores reducen, como cabe esperar, la magnitud de la ventaja de las ni\u00f1as con respecto a los ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ni\u00f1as superaron significativamente a los ni\u00f1os en ocho de los 15 pa\u00edses (la diferencia en el pa\u00eds restante no fue estad\u00edsticamente significativa). En promedio, la\u00a0<a href=\"https:\/\/www.datawrapper.de\/_\/Nbm89\/\" target=\"_blank\" rel=\"noreferrer noopener\">calidad de los centros educativos<\/a>\u00a0de estos pa\u00edses era relativamente superior a la de aquellos en los que los ni\u00f1os se situaban estad\u00edsticamente por delante de las ni\u00f1as. La calidad de los colegios se mide por la existencia y el nivel de recursos como bibliotecas, salas de profesorado, agua potable, electricidad y ordenadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, cuanto mejor es el sistema escolar en general, mejores son los resultados de las ni\u00f1as, incluso cuando entran en juego otros factores que las sit\u00faan en posici\u00f3n de desventaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en los pa\u00edses con ventaja femenina el porcentaje de estudiantes de 5\u00a0\u00ba de primaria que hab\u00edan\u00a0<a href=\"https:\/\/www.datawrapper.de\/_\/wNeAB\/\">asistido<\/a>\u00a0a preescolar sol\u00eda ser mayor. Esto corrobora las numerosas\u00a0<a href=\"https:\/\/www.worldbank.org\/en\/topic\/education\/publication\/quality-early-learning-nurturing-children-s-potential\" target=\"_blank\" rel=\"noreferrer noopener\">evidencias existentes<\/a>\u00a0sobre los\u00a0<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S027277571830596X\" target=\"_blank\" rel=\"noreferrer noopener\">beneficios a largo plazo de la educaci\u00f3n en la primera infancia<\/a>, tanto para las ni\u00f1as como para los ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ni\u00f1as tambi\u00e9n obtuvieron mejores resultados all\u00ed donde hab\u00eda una mayor presencia femenina (compa\u00f1eras, directoras y profesoras) en el entorno escolar. Los datos hacen pensar que una mayor presencia de compa\u00f1eras y modelos femeninos puede mejorar los resultados de aprendizaje de las alumnas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es fundamental garantizar que los centros educativos ofrezcan un entorno seguro y enriquecedor para la educaci\u00f3n de las ni\u00f1as. Y es igualmente importante que las familias promuevan la asistencia sistem\u00e1tica de las ni\u00f1as a clase y reduzcan al m\u00ednimo sus responsabilidades en las tareas dom\u00e9sticas que puedan interferir con sus estudios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/theconversation.com\/profiles\/pearl-s-kyei-1516252\" target=\"_blank\" rel=\"noreferrer noopener\">Pearl S. Kyei<\/a> y publicado originalmente en <a href=\"https:\/\/theconversation.com\/girls-usually-read-better-than-boys-why-this-isnt-the-case-in-some-african-countries-229924\" target=\"_blank\" rel=\"noreferrer noopener\">ingl\u00e9s<\/a> en <a href=\"https:\/\/theconversation.com\/africa\" target=\"_blank\" rel=\"noreferrer noopener\">The Conversation Africa<\/a> el 11 de junio de 2024. Traducido al espa\u00f1ol con la colaboraci\u00f3n de Casa \u00c1frica. Traducci\u00f3n: por Inmaculada Ortiz.<\/em><\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/counter.theconversation.com\/content\/232581\/count.gif?distributor=republish-lightbox-advanced\" width=\"1\" height=\"1\" style=\"border: none !important\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>En la\u00a0mayor parte del planeta,\u00a0las ni\u00f1as superan a los ni\u00f1os en capacidad de lectura. En comparaci\u00f3n con los ni\u00f1os, las ni\u00f1as tienen un mayor nivel de competencia lectora respecto al nivel esperado en cada curso. Este fen\u00f3meno se debe a\u00a0varias razones. Por un lado, se ha comprobado que las ni\u00f1as poseen mayores aptitudes naturales, pero [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":30361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2365],"tags":[3255,3254,595,664,756,950,1008,1118,1139,1325,1880,2124],"class_list":["post-30358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-educacion","tag-brecha-de-genero","tag-comprension-lectora","tag-cultura","tag-destacado","tag-educacion","tag-formacion","tag-genero","tag-igualdad","tag-infancia","tag-lectura","tag-recomendamos","tag-the-conversation-africa"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/30358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=30358"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/30358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/30361"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=30358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=30358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=30358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}