{"id":30862,"date":"2025-01-09T15:49:07","date_gmt":"2025-01-09T14:49:07","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=30862"},"modified":"2025-09-18T10:59:06","modified_gmt":"2025-09-18T09:59:06","slug":"ebrahim-hussein-y-penina-muhando-gran-literatura-en-suajili","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/musica-artes-africa\/ebrahim-hussein-y-penina-muhando-gran-literatura-en-suajili\/","title":{"rendered":"Ebrahim Hussein y Penina Muhando: gran literatura en suajili"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Desconocidos m\u00e1s all\u00e1 del \u00e1mbito ling\u00fc\u00edstico de la lengua en que escriben, el suajili, Ebrahim Hussein y Penina Muhando destacan por su calidad literaria, sus aportaciones al teatro africano y su valiente cr\u00edtica social. Dos autores tanzanos que podr\u00edan figurar en el canon de la literatura mundial si no fuera porque eligieron escribir en una lengua africana.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ebrahim_Hussein\">Ebrahim Hussein<\/a>, lo recuerdan bien los estudiantes de suajili en Tanzania porque uno de sus libros m\u00e1s c\u00e9lebres, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Kinjikitile_Ngwale\">Kinjeketile<\/a>, es de obligada lectura. Escrito en 1965, con tan s\u00f3lo 23 a\u00f1os, narra la epopeya de Kinjeketile Ngwale, quien encabez\u00f3 la rebeli\u00f3n de los Maji Maji contra la colonizaci\u00f3n alemana en 1905. Kinjeketile, al que se cre\u00eda con poderes sobrenaturales, alent\u00f3 a los campesinos a oponerse a la explotaci\u00f3n colonial, que les forzaba a cultivar algod\u00f3n para la exportaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Armados con lanzas y flechas, los rebeldes fueron masacrados por un Ej\u00e9rcito dotado de armas modernas. En dos a\u00f1os de revuelta, murieron m\u00e1s de 100.000 personas, muchas de ellas de hambre, a causa de la pol\u00edtica de tierra quemada aplicada por Gustav Alfred von G\u00f6tzen, el gobernador del \u00c1frica Alemana del Este. Kinjeketile muri\u00f3 al comienzo de la rebeli\u00f3n, en la horca, tras su captura por las tropas alemanas. Por su osad\u00eda al desafiar a un imperio europeo poderoso, Kinjeketile, al que sus seguidores llamaban Bokero, es considerado el precursor del nacionalismo tanzano, y su revuelta, un ejemplo que inspir\u00f3 a mediados del siglo pasado a los kenianos del Mau Mau, levantados contra la presencia colonial brit\u00e1nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cr\u00edtico con Julius Nyerere<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque permanece alejado del debate p\u00fablico, Ebrahim Hussein deja ver en sus obras de teatro, principalmente en Mashetani, Jogoo Kijijini y Arusi, escritas en 1971, 1976 y 1980, respectivamente, su decepci\u00f3n por el devenir de la joven rep\u00fablica bajo la presidencia de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Julius_Nyerere\">Julius Nyerere<\/a>. El autor es muy cr\u00edtico con el modelo socialista de las ujamaa (ujamaa en suajili significa trabajar y vivir juntos) desarrollado por Nyerere y la corrupci\u00f3n de los dirigentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Innovador, al punto de ser considerado uno de los creadores del teatro experimental africano, Ebrahim Hussein compagina la creaci\u00f3n literaria con la teor\u00eda. El resultado de su reflexi\u00f3n acerca del teatro y la cultura suajili se concreta en su tesis doctoral, defendida en la Universidad Humboldt de Berl\u00edn, en la entonces Rep\u00fablica Democr\u00e1tica Alemana (RDA), en 1973, titulada \u201cSobre el desarrollo del teatro en \u00c1frica del Este\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La trayectoria literaria y acad\u00e9mica de Ebrahim Hussein se parece mucho al de la escritora <a href=\"https:\/\/en.wikipedia.org\/wiki\/Penina_Muhando\">Penina Muhando<\/a>. Nacida en 1948, Muhando tambi\u00e9n opta por escribir en suajili, teorizar acerca del teatro africano, defender el panafricanismo y arremeter contra el colonialismo. Entusiasta al principio del modelo de socialismo africano desarrollado por el presidente Nyerere a partir de 1967, al cabo de unos a\u00f1os llega el desencanto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De su primera etapa, de fervor revolucionario, nos deja Hatia (Culpabilidad) en 1972. El distanciamiento del proyecto de Nyerere es evidente en otra obra de teatro, Nguzo Mama (1982). Posteriormente, la cr\u00edtica a la corrupci\u00f3n del r\u00e9gimen arrecia en Lina Ubani, escrita en 1984, y Mitumba Ndui (1989).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su carrera acad\u00e9mica tambi\u00e9n es brillante. Doctorada en Ling\u00fc\u00edstica por la Universidad de Dar es Salaam, en la que da clases, investiga sobre las artes teatrales africanas. Su obra m\u00e1s reconocida es Culture and Development: The Popular Theatre Approach in Africa, escrita en 1991.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La ingente obra de Shaaban Robert<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ebrahim Hussein y Penina Muhando son dos referentes en la literatura en suajili pero no los \u00fanicos. Del periodo precolonial, destaca <a href=\"https:\/\/en.wikipedia.org\/wiki\/Shaaban_bin_Robert\">Shaaban Robert <\/a>(1909-1962), al que se reconoce su contribuci\u00f3n a la normalizaci\u00f3n del suajili como lengua literaria. Nacionalista, pr\u00f3ximo a quien ser\u00e1 el primer presidente Nyerere, defensor de los derechos de las mujeres y de la convivencia religiosa, Shaaban Robert escribi\u00f3 poes\u00eda, ensayo, ficci\u00f3n. Una obra ingente, le\u00edda en todo el \u00e1mbito ling\u00fc\u00edstico suajili, en Tanzania pero tambi\u00e9n en Kenia y Uganda, tres pa\u00edses en que es lengua oficial. Numerosos parlantes del suajili viven en el este de la Rep\u00fablica Democr\u00e1tica del Congo, Ruanda, Burundi y el norte de Mozambique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este breve texto, no podemos dejar de citar a los tambi\u00e9n tanzanos <a href=\"https:\/\/en.wikipedia.org\/wiki\/Muhammed_Said_Abdulla\">Muhammed Said Abdullah<\/a> (1918-1991), <a href=\"https:\/\/es.wikipedia.org\/wiki\/Euphrase_Kezilahabi\">Euphrase Kezilahabi <\/a>(1944-2020) y Ben Rashid Mtobwa (1958-2008). El primero es el creador del detective Bwna Msa, protagonista de varias novelas muy populares en Tanzania y Kenia. El segundo, innovador en la poes\u00eda en suajili al no respetar las r\u00edgidas reglas m\u00e9tricas, es m\u00e1s conocido por su novela corta Rosa Mistika, escrita en 1971, prohibida en su momento al basarse en los abusos sexuales sufridos por las alumnas por parte de sus profesores. En cuanto a Mtobwa, es un autor de \u00e9xito gracias a las novelas de aventuras del investigador Joram Kirango.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abdilatif Abdalla, el poeta encarcelado<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los escritores en lengua en suajili de Kenia, destacan James Mbotela, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Abdilatif_Abdalla\">Abdilatif Abdalla<\/a>, Katama Mkangi y Ali Jemaadar Amir. Mbotela es reconocido por su obra acerca de la esclavitud, publicada en 1934, Uhuru wa Watumwa, cuya traducci\u00f3n ser\u00eda Libertad para los esclavos. Abdilatif Abdalla es un poeta, encarcelado por el r\u00e9gimen de Jomo Kenyatta de 1969 a 1972. En la c\u00e1rcel escribi\u00f3 su celebrado poema Sauti ya Dhiki (Voz de la agon\u00eda), que recibi\u00f3 el Premio de Literatura Jomo Kenyatta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a <a href=\"https:\/\/www.goodreads.com\/author\/show\/3430870.Katama_G_C_Mkangi\">Katama Mkangi <\/a>(1944-2004), tambi\u00e9n conoci\u00f3 la c\u00e1rcel por su actividad pol\u00edtica, en este caso en contra del presidente Daniel Arap Moi, que sucedi\u00f3 a Kenyatta. En la lista, sin pretensiones de ser exhaustiva, no pueden faltar Ali Jemaadar Amir (Nahodha Fikirini ) y PM Kareithi (Kaburi Bila Msalaba), relato en el que aborda la revuelta anticolonial de los Mau Mau contra los brit\u00e1nicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abdulrazak Gurnah, el Nobel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque escribe en ingl\u00e9s, no podemos dejar de citar a un escritor de origen tanzano, concretamente de la isla de Zanz\u00edbar, <a href=\"https:\/\/www.casafrica.es\/es\/persona\/abdulrazak-gurnah\">Abdulrazak Gurnah<\/a>, galardonado con el premio Nobel de Literatura en 2021. Al igual que en otros autores del \u00c1frica del Este, como el propio Ebrahim Hussein, la colonizaci\u00f3n alemana, y sus perniciosos efectos sociales y econ\u00f3micos en la sociedad a la que pretenden someter, alimenta la literatura de Gurnah.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dos de sus obras, Paradise (Para\u00edso en la edici\u00f3n en espa\u00f1ol), escrita en 1994, y Afterlives (La vida despu\u00e9s), del 2020, Gurnah recrea un universo de violencia, despotismo y arbitrariedad, en el que la vida de los africanos, tenidos como subhumanos, no cuenta. En Afterlives, el escritor, formado en universidades brit\u00e1nicas, recrea el levantamiento de los Maji Maji contra el poder alem\u00e1n, en una guerra desigual que dej\u00f3 miles de muertos. \u201cLos alemanes han matado a tanta gente que el pa\u00eds est\u00e1 lleno de cr\u00e1neos y el suelo est\u00e1 empapado de sangre\u201d, escribe Gurnah. Los lectores en suajili pueden leer Paradise en dicha lengua, con el t\u00edtulo de Peponi, en una traducci\u00f3n de Ida Hadjivayanis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desconocidos m\u00e1s all\u00e1 del \u00e1mbito ling\u00fc\u00edstico de la lengua en que escriben, el suajili, Ebrahim Hussein y Penina Muhando destacan por su calidad literaria, sus aportaciones al teatro africano y su valiente cr\u00edtica social. Dos autores tanzanos que podr\u00edan figurar en el canon de la literatura mundial si no fuera porque eligieron escribir en una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[82,595,664,1259,1352,1880,2071,2096,2102],"class_list":["post-30862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica-artes-africa","tag-africa","tag-cultura","tag-destacado","tag-kenia","tag-literatura","tag-recomendamos","tag-suajili","tag-tanzania","tag-teatro"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/30862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=30862"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/30862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/30864"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=30862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=30862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=30862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}