{"id":31014,"date":"2025-02-03T16:43:17","date_gmt":"2025-02-03T15:43:17","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=31014"},"modified":"2025-02-07T10:44:39","modified_gmt":"2025-02-07T09:44:39","slug":"por-que-los-jovenes-cientificos-africanos-deberian-ayudar-en-la-revision-de-la-calidad-de-la-investigacion-sobre-el-cambio-climatico","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/sostenibilidad-energia-africa\/por-que-los-jovenes-cientificos-africanos-deberian-ayudar-en-la-revision-de-la-calidad-de-la-investigacion-sobre-el-cambio-climatico\/","title":{"rendered":"Por qu\u00e9 los j\u00f3venes cient\u00edficos africanos deber\u00edan ayudar en la revisi\u00f3n de la calidad de la investigaci\u00f3n sobre el cambio clim\u00e1tico"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La investigaci\u00f3n cient\u00edfica es esencial para abordar la crisis clim\u00e1tica. <a href=\"https:\/\/www.ipcc.ch\/\">El Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico (IPCC)<\/a>, un \u00f3rgano de las Naciones Unidas, eval\u00faa lo investigado sobre el cambio clim\u00e1tico en sus <a href=\"https:\/\/www.ipcc.ch\/reports\/\">informes<\/a> de evaluaci\u00f3n regulares. Estos <a href=\"https:\/\/www.ipcc.ch\/synthesis-report\/\">informes<\/a> reflejan el consenso cient\u00edfico sobre las causas y el impacto del cambio clim\u00e1tico y sobre sus posibles soluciones.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los informes no son solo publicaciones cient\u00edficas, sino que tambi\u00e9n informan sobre pol\u00edticas a nivel global, nacional y regional relacionadas con el <a href=\"https:\/\/study.com\/academy\/lesson\/anthropogenic-climate-change-definition-factors.html#:%7E:text=Anthropogenic%20causes%20of%20climate%20change%20are%20human%20activities%20that%20add,industry%2C%20agriculture%2C%20and%20transportation.\">cambio clim\u00e1tico antropog\u00e9nico<\/a> (causado por el ser humano) y sobre el estado del medioambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los informes pasan, adem\u00e1s, por un riguroso <a href=\"https:\/\/authorservices.wiley.com\/Reviewers\/journal-reviewers\/what-is-peer-review\/index.html\">sistema de revisi\u00f3n por expertos<\/a> para asegurar que su <a href=\"https:\/\/doi.org\/10.1098\/rsos.140540\">credibilidad<\/a> y m\u00e9rito cient\u00edfico sean fiables antes de que se publiquen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de evaluaci\u00f3n del Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico est\u00e1 encabezado por <a href=\"https:\/\/gc.copernicus.org\/articles\/3\/89\/2020\/gc-3-89-2020.html\">investigadores de pa\u00edses de ingresos altos<\/a> e investigadores consolidados. Pero tambi\u00e9n es importante el papel de los <a href=\"https:\/\/www.academiccareermaps.org\/glossary\/early-career-researcher-ecr#:%7E:text=An%20ERC%20is%20generally%20considered,postdoctorate%3B%20Transition%20to%20independent%20researcher.\">investigadores y cient\u00edficos noveles<\/a> (que generalmente son aquellos que han finalizado un doctorado en los \u00faltimos ocho a\u00f1os) en la investigaci\u00f3n para la prevenci\u00f3n de una cat\u00e1strofe clim\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tener perspectivas nuevas, ayudan a que los informes sean m\u00e1s equilibrados, lo que puede <a href=\"https:\/\/doi.org\/10.1002\/asi.22784\">contrarrestar algunos de los prejuicios<\/a> que tienen los investigadores senior, mejorando as\u00ed <a href=\"https:\/\/doi.org\/10.1187\/cbe.10-10-0127\">la calidad de las publicaciones cient\u00edficas<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluir a los investigadores noveles en el proceso de revisi\u00f3n por expertos les ayuda a <a href=\"https:\/\/www.nature.com\/articles\/d41586-018-05956-7\">mejorar habilidades fundamentales<\/a> y fomenta su <a href=\"https:\/\/doi.org\/10.1038\/d41586-022-00216-1\">desarrollo profesional<\/a>. Beneficia a la ciencia y es esencial para que los <a href=\"https:\/\/www.lse.ac.uk\/granthaminstitute\/news\/unpacking-inclusive-climate-action\/\">debates clim\u00e1ticos sean justos e inclusivos<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos cient\u00edficos y ge\u00f3grafos que han estudiado los informes sobre las revisiones sobre el clima a nivel mundial llevadas a cabo por investigadores que est\u00e1n en sus primeros a\u00f1os de carrera profesional realizados entre 2018 y 2021. Encuestamos a m\u00e1s de 600 investigadores noveles de m\u00e1s de 70 pa\u00edses y los <a href=\"https:\/\/www.frontiersin.org\/journals\/climate\/articles\/10.3389\/fclim.2024.1395040\/full\">resultados<\/a> mostraron que los investigadores noveles redactaron, de media, 2&nbsp;400 rese\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada informe del Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico <a href=\"https:\/\/apps.ipcc.ch\/outreach\/documents\/675\/1674726554.pdf\">puede llegar a recibir entre 78&nbsp;000<\/a> y <a href=\"https:\/\/www.ipcc.ch\/site\/assets\/uploads\/2018\/02\/FS_review_process.pdf\">140&nbsp;000 rese\u00f1as de expertos<\/a> en total, por lo que la aportaci\u00f3n de los investigadores noveles es insignificante en comparaci\u00f3n. Y aun as\u00ed, aproximadamente el 36% de las rese\u00f1as hechas por estos investigadores mejoraron el valor y el m\u00e9rito cient\u00edfico de los informes al se\u00f1alar investigaciones inexactas, interpretaciones incorrectas de los datos, y otros errores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es por todo esto por lo que el sistema de revisi\u00f3n por expertos es tan importante, porque sin las revisiones el m\u00e9rito cient\u00edfico de los informes se ver\u00eda afectado de forma negativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.frontiersin.org\/journals\/climate\/articles\/10.3389\/fclim.2024.1395040\/full\">Los resultados de la encuesta<\/a> tambi\u00e9n mostraron que incluir a los investigadores noveles en el proceso de revisi\u00f3n por expertos mejora sus habilidades de revisi\u00f3n y les aporta crecimiento profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, estos resultados muestran a su vez que los investigadores noveles de <a href=\"https:\/\/blogs.worldbank.org\/en\/opendata\/world-bank-country-classifications-by-income-level-for-2024-2025\">pa\u00edses de ingreso bajo y mediano bajo<\/a> <a href=\"https:\/\/www.frontiersin.org\/journals\/climate\/articles\/10.3389\/fclim.2024.1395040\/full\">apenas estaban representados<\/a> en el proceso de revisi\u00f3n por expertos. Conformaban <a href=\"https:\/\/www.frontiersin.org\/journals\/climate\/articles\/10.3389\/fclim.2024.1395040\/full\">menos del 1%<\/a> del total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores noveles son los cient\u00edficos del ma\u00f1ana. Son ellos qui\u00e9nes desarrollar\u00e1n nuevas investigaciones. A pesar de los <a href=\"https:\/\/usaf.ac.za\/why-emerging-researchers-need-to-be-supported\/\">continuos esfuerzos<\/a> para incluir a investigadores africanos en la ciencia mundial, existe una falta de investigadores emergentes, lo que muestra que debemos emplear m\u00e1s recursos y esfuerzos en solucionar este problema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los problemas a los que se enfrentan los investigadores noveles<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ojos de los investigadores consolidados, los investigadores noveles <a href=\"https:\/\/doi.org\/10.1038\/d41586-018-06632-6\">carecen de la pericia<\/a> necesaria para realizar las rese\u00f1as. Su acceso a becas y oportunidades es menor porque no est\u00e1n consolidados en su carrera profesional y a\u00fan no tienen una red de contactos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La revisi\u00f3n de expertos es una habilidad que debe aprenderse y que requiere una formaci\u00f3n o una mentor\u00eda por parte de un investigador senior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos investigadores noveles rese\u00f1an al colaborando con investigadores senior sin recibir reconocimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores noveles de pa\u00edses en desarrollo se enfrentan a retos sistem\u00e1ticos adicionales. Por ejemplo, desde 1990 hasta 2020, el <a href=\"https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/17565529.2021.1976609\">78% de los fondos para la realizaci\u00f3n de estudios sobre el cambio clim\u00e1tico en \u00c1frica<\/a> se asignaron a instituciones en Europa y Norteam\u00e9rica. A este desequilibro de financiaci\u00f3n se le a\u00f1ade <a href=\"https:\/\/www.wri.org\/research\/climate-cooperation-disparities-analysis-global-south-climate-change-mitigation\">una representaci\u00f3n limitada en los debates de pol\u00edticas clave sobre el clima como las cumbres de la COP de la ONU.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto limita la capacidad de los investigadores africanos para llevar a cabo estudios enfocados a nivel local. Por consiguiente, no pueden influir de forma efectiva en las pol\u00edticas que afectan directamente a sus regiones. La inclusividad y relevancia de las respuestas ante el clima mundial resultan muy limitadas por este motivo. Los investigadores africanos pueden intentar emigrar a pa\u00edses desarrollados, reflejando as\u00ed la \u201c<a href=\"https:\/\/blogs.lse.ac.uk\/africaatlse\/2024\/03\/19\/africas-migration-and-brain-drain-revisited\/\">fuga de cerebros<\/a>\u201d de la poblaci\u00f3n activa formada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El apoyo que necesitan los investigadores noveles africanos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las experiencias de los investigadores noveles africanos est\u00e1n definidas por contextos socioecon\u00f3micos diferenciados y por los retos medioambientales. Estos investigadores pueden sacar a la luz el impacto clim\u00e1tico espec\u00edfico por regiones y conceder estrategias que de otra manera se podr\u00edan ignorar, lo que es especialmente importante <a href=\"https:\/\/wmo.int\/news\/media-centre\/africa-faces-disproportionate-burden-from-climate-change-and-adaptation-costs\">dado que \u00c1frica est\u00e1 muy afectada por el cambio clim\u00e1tico.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comunidad cient\u00edfica debe incluir a los investigadores noveles africanos en sus procesos de revisi\u00f3n para fomentar que la comunidad cient\u00edfica sea m\u00e1s inclusiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se deben poner en marcha <a href=\"https:\/\/www.frontiersin.org\/journals\/climate\/articles\/10.3389\/fclim.2024.1395040\/full\">formaciones regladas<\/a>, mentor\u00edas guiadas y colaborativas, y oportunidades de crear redes de contacto. El hecho de proporcionar estas oportunidades de manera efectiva incluir\u00eda formalmente a los investigadores noveles africanos en el proceso de revisi\u00f3n por expertos de los informes regulares sobre el cambio clim\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se deben crear redes de contacto de manera m\u00e1s formal para que suplan las necesidades de los investigadores noveles. Esto puede incluir que se celebren talleres regionales o foros en l\u00ednea para fomentar las interacciones, la colaboraci\u00f3n, el sentimiento de comunidad y de un objetivo com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los programas de mentor\u00eda y formaci\u00f3n se deben adaptar a los retos espec\u00edficos y a las diferencias culturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se debe llegar a acuerdos para que el acceso a los recursos sea equitativo a la hora de crear investigaciones colaborativas a nivel internacional. Es necesario para que las investigaciones sean de calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Texto de varios autores: <a href=\"https:\/\/theconversation.com\/profiles\/christel-dorothee-hansen-1235446\">Christel Dorothee Hansen<\/a>, <a href=\"https:\/\/theconversation.com\/profiles\/chukwuma-moses-anoruo-1282303\">Chukwuma Moses Anoruo<\/a>, <a href=\"https:\/\/theconversation.com\/profiles\/olumide-david-onafeso-2267712\">Olumide David Onafeso<\/a>, et al. El investigador novel <a href=\"https:\/\/theconversation.com\/profiles\/r-arun-prasath-2262207\">R. Arun Prasath<\/a> es coautor de este art\u00edculo.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo publicado originalmente en ingl\u00e9s en&nbsp;<a href=\"https:\/\/theconversation.com\/why-africas-young-scientists-should-help-check-the-quality-of-climate-change-research-244719\">The Conversation<\/a>&nbsp;y traducido al espa\u00f1ol por Marina Rodr\u00edguez Romero para&nbsp;<\/em><a href=\"https:\/\/www.casafrica.es\/es\"><em>Casa \u00c1frica<\/em><\/a><em>.<\/em><\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/counter.theconversation.com\/content\/244719\/count.gif?distributor=republish-lightbox-advanced\" width=\"1\" height=\"1\" style=\"border: none !important\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<pre class=\"wp-block-code\"><code><\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n cient\u00edfica es esencial para abordar la crisis clim\u00e1tica. El Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico (IPCC), un \u00f3rgano de las Naciones Unidas, eval\u00faa lo investigado sobre el cambio clim\u00e1tico en sus informes de evaluaci\u00f3n regulares. Estos informes reflejan el consenso cient\u00edfico sobre las causas y el impacto del cambio clim\u00e1tico y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[2687,465,664,3163,757,3223,1238,1880,2106],"class_list":["post-31014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilidad-energia-africa","tag-cambio-climatico-2","tag-ciencia","tag-destacado","tag-educacion-cientifica","tag-educacion-en-africa","tag-innovacion-africana","tag-juventud-en-africa","tag-recomendamos","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/31014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=31014"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/31014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/31015"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=31014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=31014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=31014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}