{"id":35349,"date":"2026-01-26T12:22:07","date_gmt":"2026-01-26T11:22:07","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=35349"},"modified":"2026-02-09T11:53:17","modified_gmt":"2026-02-09T10:53:17","slug":"espana-y-senegal-en-el-horizonte-de-la-seguridad-y-el-desarrollo","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/fr\/migraciones-sociedad-africana\/espana-y-senegal-en-el-horizonte-de-la-seguridad-y-el-desarrollo\/","title":{"rendered":"Espa\u00f1a y Senegal en el horizonte de la seguridad y el desarrollo"},"content":{"rendered":"\n<p><em>Las migraciones africanas a trav\u00e9s de la Ruta Atl\u00e1ntica se han reducido significativamente en 2025. Uno de los motivos que da respuesta a este cambio es la creciente cooperaci\u00f3n de Espa\u00f1a con Senegal en el \u00e1mbito de seguridad. Con motivo de la reciente noticia sobre la entrega del gobierno espa\u00f1ol de dos patrulleras a las fuerzas de seguridad del gobierno senegal\u00e9s, realizamos una aproximaci\u00f3n a c\u00f3mo se configuran las relaciones entre Espa\u00f1a y los pa\u00edses africanos desde un enfoque de seguridad y desarrollo, recordando los Planes \u00c1frica y en \u00faltimo lugar, la Estrategia Espa\u00f1a-\u00c1frica, los cuales son el marco de referencia para los posteriores marcos de asociaci\u00f3n que se han elaborado para las relaciones entre ambos pa\u00edses. Es por ello que anticipamos que el \u00faltimo Marco de Asociaci\u00f3n Pa\u00eds Senegal 2024-2028, a\u00fan en fase de elaboraci\u00f3n, estar\u00e1 en sinton\u00eda con los planes predecesores y con su marco de referencia la Estrategia 2025-2028, dise\u00f1ando ejes de actuaci\u00f3n cuyo \u00faltimo fin sea la prevenci\u00f3n de las migraciones africanas hacia Espa\u00f1a.<\/em><\/p>\n\n\n\n<p>A comienzos de diciembre del pasado a\u00f1o el ministro del Interior del Gobierno de Espa\u00f1a, Fernando Grande-Marlaska, viaj\u00f3 a Dakar, donde hizo entrega oficial de dos naves de patrulla costera \u201c<a href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/interior\/paginas\/2025\/021225-marlaska-patrulleras-senegal.aspx\">para contribuir al \u2018trabajo clave\u2019 en prevenci\u00f3n migratoria<\/a>\u201d que est\u00e1n realizando las fuerzas de seguridad senegalesas. La eficacia de las operaciones de seguridad conjuntas entre los dos pa\u00edses para frenar la migraci\u00f3n mar\u00edtima hacia las Islas Canarias queda demostrada por la disminuci\u00f3n del n\u00famero de llegadas a trav\u00e9s de la Ruta Atl\u00e1ntica en 2025<a href=\"#_ftn1\" id=\"_ftnref1\"><sup>[1]<\/sup><\/a>. Sin embargo, esto no significa que se hayan reducido los intentos de migrar hacia Europa, ya que<a href=\"https:\/\/www.infomigrants.net\/fr\/post\/67210\/route-des-canaries--pres-de-700-migrants-secourus-en-une-semaine-au-large-du-senegal\"> <\/a><a href=\"https:\/\/www.infomigrants.net\/fr\/post\/67210\/route-des-canaries--pres-de-700-migrants-secourus-en-une-semaine-au-large-du-senegal\">la intensificaci\u00f3n de los controles fronterizos en Senegal y Mauritania <\/a><a href=\"https:\/\/www.infomigrants.net\/fr\/post\/67210\/route-des-canaries--pres-de-700-migrants-secourus-en-une-semaine-au-large-du-senegal\">ha trasladado los puntos de partida hacia Europa, saliendo ahora desde Gambia y Guinea<\/a>, lo que, respecto a Guinea, aumenta el riesgo a morir debido a su lejan\u00eda con el archipi\u00e9lago canario.<\/p>\n\n\n\n<p>Entre 2024 y 2025 hemos sido testigos de una creciente colaboraci\u00f3n entre Espa\u00f1a y Senegal en materia de seguridad y defensa<a href=\"#_ftn2\" id=\"_ftnref2\"><sup>[2]<\/sup><\/a>. Pero al margen de operaciones espec\u00edficas, cabe preguntarse c\u00f3mo se articulan las relaciones bilaterales entre Espa\u00f1a y Senegal. A d\u00eda de hoy, estas se estructuran bajo el marco de la<a href=\"https:\/\/www.exteriores.gob.es\/es\/Comunicacion\/Noticias\/Paginas\/Noticias\/Estrategia-Espa%C3%B1a-%C3%81frica-2025-2028-relaci%C3%B3n-estrat%C3%A9gica.aspx\"> <\/a><a href=\"https:\/\/www.exteriores.gob.es\/es\/Comunicacion\/Noticias\/Paginas\/Noticias\/Estrategia-Espa%C3%B1a-%C3%81frica-2025-2028-relaci%C3%B3n-estrat%C3%A9gica.aspx\">Estrategia Espa\u00f1a-\u00c1frica 2025-2028<\/a>, una hoja de ruta elaborada por el gobierno espa\u00f1ol que organiza las relaciones bilaterales y multilaterales con distintos actores africanos (gobiernos nacionales, organismos regionales e internacionales y actores no estatales). Esta re\u00fane los objetivos y prioridades de la pol\u00edtica exterior espa\u00f1ola hacia el continente africano, as\u00ed como esboza las l\u00edneas de acci\u00f3n a desarrollar para los pr\u00f3ximos cuatro a\u00f1os.<\/p>\n\n\n\n<p>La Estrategia Espa\u00f1a-\u00c1frica, que a su vez sigue las pautas del<a href=\"https:\/\/www.exteriores.gob.es\/es\/PoliticaExterior\/Documents\/Cooperaci%C3%B3n%20para%20el%20desarrollo\/Plan%20Director%20de%20la%20Cooperaci%C3%B3n%20Espa%C3%B1ola_FINAL.pdf\"> <\/a><a href=\"https:\/\/www.exteriores.gob.es\/es\/PoliticaExterior\/Documents\/Cooperaci%C3%B3n%20para%20el%20desarrollo\/Plan%20Director%20de%20la%20Cooperaci%C3%B3n%20Espa%C3%B1ola_FINAL.pdf\">Plan Director de la Cooperaci\u00f3n Espa\u00f1ola para el Desarrollo Sostenible y la Solidaridad Global 2024-2027<\/a>, es la continuaci\u00f3n de los anteriormente llamados Planes \u00c1frica<a href=\"#_ftn3\" id=\"_ftnref3\"><sup>[3]<\/sup><\/a>. Todos ellos han estado influenciados por los contextos en los que surgieron, por lo que no es de extra\u00f1ar que hayan adoptado el nexo seguridad-desarrollo que encontramos tanto a nivel internacional en el marco de las Naciones Unidas como en la esfera de la Uni\u00f3n Europea<a href=\"#_ftn4\" id=\"_ftnref4\"><sup>[4]<\/sup><\/a>. En este \u00faltimo caso destacamos <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/ES\/TXT\/?uri=legissum:4413648\">La Estrategia Global de la Pol\u00edtica Exterior y de Seguridad de la Uni\u00f3n Europea<\/a>, en donde observamos c\u00f3mo seguridad y desarrollo se conciben como variables interdependientes, empleando un lenguaje b\u00e9lico en el que convergen la seguridad interior y la seguridad exterior y que sirve para justificar la expansi\u00f3n de la visi\u00f3n europea m\u00e1s all\u00e1 de sus fronteras:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Los objetivos, e incluso la propia existencia de nuestra Uni\u00f3n est\u00e1n en entredicho. Y sin embargo nunca tanto como ahora han necesitado nuestros ciudadanos y el resto del mundo una Uni\u00f3n Europea fuerte. Nuestra regi\u00f3n, en su extensi\u00f3n m\u00e1s amplia, es cada vez m\u00e1s inestable e insegura. Las crisis dentro y fuera de nuestras fronteras est\u00e1n afectando directamente a la vida de nuestros ciudadanos (&#8230;) \u00abGlobal\u00bb no debe entenderse \u00fanicamente en el sentido geogr\u00e1fico: tambi\u00e9n hace referencia al amplio espectro de pol\u00edticas e instrumentos que promueve la estrategia, que se centra tanto en las capacidades militares y antiterroristas como en las oportunidades de empleo, en unas sociedades inclusivas y en la protecci\u00f3n de los derechos humanos. Contempla la consolidaci\u00f3n de la paz y la resiliencia de las sociedades y los Estados, en Europa y en los pa\u00edses vecinos<a href=\"#_ftn5\" id=\"_ftnref5\"><sup>[5]<\/sup><\/a>.<\/p>\n<\/blockquote>\n\n\n\n<p>Es en sinton\u00eda con este escenario de conflicto en el que tanto los Planes \u00c1frica como la Estrategia Espa\u00f1a-\u00c1frica dedican especial atenci\u00f3n a las relaciones con Senegal, siguiendo su designaci\u00f3n como \u201cpa\u00eds prioritario\u201d en los Planes Directores de referencia<a href=\"#_ftn6\" id=\"_ftnref6\"><sup>[6]<\/sup><\/a>. Esta asignaci\u00f3n corresponde, seg\u00fan el Gobierno espa\u00f1ol, al preponderante papel de Senegal en la regi\u00f3n de \u00c1frica Occidental y a su proximidad con las Islas Canarias<a href=\"#_ftn7\" id=\"_ftnref7\"><sup>[7]<\/sup><\/a>. Es por ello que para afianzar las relaciones con el pa\u00eds africano se han cerrado acuerdos como el<a href=\"https:\/\/www.boe.es\/eli\/es\/ai\/2006\/10\/10\/(3)\"> Marco de Cooperaci\u00f3n de 2006<\/a>, que contemplaba actividades de cooperaci\u00f3n en \u00e1mbitos como \u201clos servicios sociales de base\u201d, \u201cel acondicionamiento de infraestructuras de desarrollo local\u201d, \u201cla protecci\u00f3n de los derechos humanos y de los grupos sociales m\u00e1s vulnerables\u201d y \u201cel refuerzo de las estructuras democr\u00e1ticas y de la sociedad civil\u201d entre otras. Otro ejemplo de ellos son los acuerdos alcanzados en 2021 en torno a la migraci\u00f3n que formaban parte del III Plan \u00c1frica (2020-2023) y cuyo objetivo era \u201c<a href=\"https:\/\/www.mites.gob.es\/es\/mundo\/consejerias\/senegal\/novedades\/archivos\/memorandos.htm\">atacar la lacra de la emigraci\u00f3n irregular y ayudar a garantizar la seguridad de las fronteras<\/a>\u201d. La reciente Estrategia Espa\u00f1a-\u00c1frica, en l\u00ednea con el Plan Director 2024-2027, establece la elaboraci\u00f3n de un Marco de Asociaci\u00f3n Espa\u00f1a-Senegal 2024-2028 que refleje la creciente cooperaci\u00f3n entre ambos pa\u00edses y de la que hemos sido testigos a lo largo de 2024 y 2025.<\/p>\n\n\n\n<p>Nos referimos no solo al refuerzo de operaciones de seguridad conjuntas, sino a las iniciativas acordadas durante la visita del presidente espa\u00f1ol Pedro S\u00e1nchez a Senegal en agosto de 2024: la ampliaci\u00f3n del programa de migraci\u00f3n circular y la puesta en marcha de la Alianza \u00c1frica Avanza. La primera consiste en la selecci\u00f3n y contrataci\u00f3n de trabajadores en Senegal para cubrir las vacantes laborales estacionales, de campa\u00f1a o de temporada del mercado espa\u00f1ol.\u00a0 Seg\u00fan la ministra a cargo de la cartera de Inclusi\u00f3n, Seguridad Social y Migraciones, Elma Saiz, se trata de \u201c<a href=\"https:\/\/www.inclusion.gob.es\/ca\/w\/elma-saiz-reafirma-en-senegal-la-apuesta-de-espana-por-los-proyectos-de-migracion-circular-una-formula-en-la-que-todos-ganamos-\">ofrecer una alternativa a la migraci\u00f3n irregular<\/a>\u201d. Sin embargo, el volumen de solicitudes para participar en el programa en 2025 super\u00f3 con creces la oferta, pues en tan solo 48 horas<a href=\"https:\/\/africacheck.org\/fr\/fact-checks\/fiches-dinformation\/explainer-decryptage-senegal-comprendre-la-migration-circulaire-avec-espagne\"> <\/a><a href=\"https:\/\/africacheck.org\/fr\/fact-checks\/fiches-dinformation\/explainer-decryptage-senegal-comprendre-la-migration-circulaire-avec-espagne\">se recibieron alrededor de 10.000 candidaturas para un anuncio de 350 puestos de trabajo<\/a>. Adem\u00e1s, Senegal ser\u00e1 el pa\u00eds piloto donde dar\u00e1 comienzo la Alianza \u00c1frica Avanza, que se basa en la internacionalizaci\u00f3n de empresas espa\u00f1olas mediante inversiones en la regi\u00f3n para as\u00ed fomentar \u201c<a href=\"https:\/\/comercio.gob.es\/es-es\/estrategia_internacionalizacion\/Paginas\/Estrategia_Horizonte_Africa.aspx\">el desarrollo de la actividad productiva y la generaci\u00f3n del empleo en sectores tractores en pa\u00edses africanos<\/a>\u201d, lo que pretende fomentar el desarrollo nacional y crear oportunidades laborales, para como fin \u00faltimo, disminuir la migraci\u00f3n hacia Espa\u00f1a. Aunque las relaciones entre Espa\u00f1a y Senegal han contado con acuerdos bilaterales propios en donde se trazan de manera singular las prioridades y las l\u00edneas de acci\u00f3n, estos se han configurado bajo el paraguas de las distintas estrategias de pol\u00edtica exterior nacionales as\u00ed como han estado alineados con la visi\u00f3n de la Uni\u00f3n Europea. Hasta la fecha, la voluntad de colaboraci\u00f3n por parte de Espa\u00f1a se ha enraizado en el nexo de seguridad-desarrollo, un enfoque que, en cuanto a materia de migraci\u00f3n se refiere, ha contado con el apoyo del gobierno senegal\u00e9s. Es por ello que anticipamos que los ejes de actuaci\u00f3n que se recojan en el pr\u00f3ximo Marco de Asociaci\u00f3n seguir\u00e1n nublando el futuro de una relaci\u00f3n bilateral verdaderamente horizontal al fundamentarse en una l\u00f3gica que obra a favor de la promoci\u00f3n de los intereses propios y del control de las fronteras a trav\u00e9s de operaciones de seguridad y del dise\u00f1o de proyectos de cooperaci\u00f3n al desarrollo.<\/p>\n\n\n\n<p><em>Art\u00edculo redactado por <a href=\"https:\/\/www.casafrica.es\/es\/persona\/indhira-garcia-belda\" target=\"_blank\" rel=\"noreferrer noopener\">Indhira Garc\u00eda Belda<\/a>, de la Universidad Loyola de Andaluc\u00eda, y <a href=\"https:\/\/www.casafrica.es\/es\/persona\/maria-angeles-alaminos-hervas-0\" target=\"_blank\" rel=\"noreferrer noopener\">Mar\u00eda \u00c1ngeles Alaminos Herv\u00e1s<\/a>, de la Universidad Loyola Andaluc\u00eda, GEA, UNISCI.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"743\" height=\"99\" src=\"https:\/\/www.esafrica.es\/wp-content\/uploads\/2026\/01\/image.png\" alt=\"\" class=\"wp-image-35358\" srcset=\"https:\/\/www.esafrica.es\/wp-content\/uploads\/2026\/01\/image.png 743w, https:\/\/www.esafrica.es\/wp-content\/uploads\/2026\/01\/image-300x40.png 300w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\"><sup>[1]<\/sup><\/a> Para consultar los datos, v\u00e9anse las publicaciones quincenales \u201cInmigraci\u00f3n irregular\u201d publicadas por el Ministerio del Interior:<a href=\"https:\/\/www.interior.gob.es\/opencms\/es\/prensa\/balances-e-informes\/\"> <\/a><a href=\"https:\/\/www.interior.gob.es\/opencms\/es\/prensa\/balances-e-informes\/\">Ministerio del Interior | Balances e Informes<\/a>.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\"><sup>[2]<\/sup><\/a> Para un mayor detalle sobre la cooperaci\u00f3n en seguridad v\u00e9ase el comunicado publicado en<a href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/interior\/paginas\/2025\/021225-marlaska-patrulleras-senegal.aspx\"> <\/a><a href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/interior\/paginas\/2025\/021225-marlaska-patrulleras-senegal.aspx\">La Moncloa<\/a>.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\"><sup>[3]<\/sup><\/a> Plan \u00c1frica 2006-2008, II Plan \u00c1frica 2009-2012, III Plan \u00c1frica 2020-2023.<\/p>\n\n\n\n<p><a href=\"#_ftnref4\" id=\"_ftn4\"><sup>[4]<\/sup><\/a> Un ejemplo del nexo seguridad-desarrollo es el informe de las Naciones Unidas emitido por el entonces Secretario General Kofi A. Annan:<a href=\"https:\/\/www.un.org\/spanish\/largerfreedom\/report-largerfreedom.pdf\"> <\/a><a href=\"https:\/\/www.un.org\/spanish\/largerfreedom\/report-largerfreedom.pdf\">Un concepto m\u00e1s amplio de la libertad: desarrollo, seguridad y derechos humanos para todos<\/a> (2005).<\/p>\n\n\n\n<p><a href=\"#_ftnref5\" id=\"_ftn5\"><sup>[5]<\/sup><\/a> Pr\u00f3logo de la Alta Representante de la Uni\u00f3n Europea para Asuntos Exteriores y Pol\u00edtica de Seguridad Federica Mogherini.<\/p>\n\n\n\n<p><a href=\"#_ftnref6\" id=\"_ftn6\"><sup>[6]<\/sup><\/a> Plan \u00c1frica 2006-2008, correspondencia con el II Plan Director de la Cooperaci\u00f3n Espa\u00f1ola 2005-2008; Plan \u00c1frica II 2009-2012, correspondencia con el III Plan Director de la Cooperaci\u00f3n Espa\u00f1ola 2009-2012; Plan \u00c1frica III 2020-2023, correspondencia con el V Plan Director de la Cooperaci\u00f3n Espa\u00f1ola 2018-2021; Estrategia Espa\u00f1a-\u00c1frica 2025-2028, correspondencia con el VI Plan Director de la Cooperaci\u00f3n Espa\u00f1ola para el Desarrollo Sostenible y la Solidaridad Global 2024-2027.<\/p>\n\n\n\n<p><a href=\"#_ftnref7\" id=\"_ftn7\"><sup>[7]<\/sup><\/a> Seg\u00fan lo expuesto por el gobierno espa\u00f1ol, Senegal ocupa un lugar distinguido dentro de la regi\u00f3n de \u00c1frica Occidental con motivo del afianzamiento de la democracia, as\u00ed como por el crecimiento econ\u00f3mico que estaba atravesando en aquel periodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las migraciones africanas a trav\u00e9s de la Ruta Atl\u00e1ntica se han reducido significativamente en 2025. Uno de los motivos que da respuesta a este cambio es la creciente cooperaci\u00f3n de Espa\u00f1a con Senegal en el \u00e1mbito de seguridad. Con motivo de la reciente noticia sobre la entrega del gobierno espa\u00f1ol de dos patrulleras a las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[82,646,664,738,3187,1491,2381,1802,1880,3176,2001],"class_list":["post-35349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-migraciones-sociedad-africana","tag-africa","tag-desarrollo","tag-destacado","tag-economia2","tag-inmigracion-irregular","tag-migraciones","tag-politica-3","tag-politica","tag-recomendamos","tag-ruta-atlantica","tag-senegal"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/35349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/comments?post=35349"}],"version-history":[{"count":5,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/35349\/revisions"}],"predecessor-version":[{"id":35369,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/posts\/35349\/revisions\/35369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media\/35352"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/media?parent=35349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/categories?post=35349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/fr\/wp-json\/wp\/v2\/tags?post=35349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}