{"id":17309,"date":"2022-10-31T12:33:50","date_gmt":"2022-10-31T11:33:50","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=17309"},"modified":"2025-07-28T09:39:22","modified_gmt":"2025-07-28T08:39:22","slug":"la-amenaza-climatica-no-es-futuro-ya-es-presente","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/pt-pt\/sostenibilidad-energia-africa\/la-amenaza-climatica-no-es-futuro-ya-es-presente\/","title":{"rendered":"<strong>La amenaza clim\u00e1tica no es futuro, ya es presente<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>En poco m\u00e1s de una semana, Egipto acoger\u00e1 la COP27, la cumbre clim\u00e1tica en la que los pa\u00edses africanos exigir\u00e1n, y con raz\u00f3n, ayuda financiera y apoyo para hacer frente a unos fen\u00f3menos clim\u00e1ticos que ya est\u00e1 causando muertes, da\u00f1os y enormes p\u00e9rdidas<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faltan ya muy pocos d\u00edas para que se celebre en Egipto, concretamente en Sharm-el Sheik, la nueva cumbre clim\u00e1tica que reunir\u00e1 a toda la comunidad internacional, la <a href=\"https:\/\/cop27.eg\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\">COP 27<\/a>. Entre los pr\u00f3ximos 7 y 18 de noviembre se reunir\u00e1n miles de responsables pol\u00edticos de cerca de 200 pa\u00edses, de la sociedad civil y el mundo empresarial, en una nueva Conferencia de las Partes sobre Cambio Clim\u00e1tico auspiciada por <a href=\"https:\/\/www.un.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Naciones Unidas<\/a>, que en esta ocasi\u00f3n tiene un marcado cariz africano no solo provocado por el hecho de que se celebre en el continente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta llamada \u2018COP africana\u2019 vamos a escuchar muchas veces un concepto que hasta ahora no hab\u00eda aparecido tanto: el de las \u2018p\u00e9rdidas y da\u00f1os\u2019. Porque la del cambio clim\u00e1tico, no nos enga\u00f1emos, no es una amenaza del futuro. Es presente. Est\u00e1 ocurriendo ya hoy, y en \u00c1frica, nuestro continente vecino, teniendo unas consecuencias de dimensiones colosales. De hecho, est\u00e1 directamente matando gente. En este 2022, el cambio clim\u00e1tico ha provocado ya \u2018p\u00e9rdidas y da\u00f1os\u2019 de norte a sur del continente. Perm\u00edtanme enumerarle algunos ejemplos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nigeria: M\u00e1s de 600 fallecidos en las peores inundaciones que el pa\u00eds ha sufrido en los \u00faltimos diez a\u00f1os. 1,3 millones de personas se han visto obligadas a dejar su casa, y un total de 2,5 millones de personas est\u00e1n en estos momentos en necesidad de ayuda humanitaria urgente. Unas lluvias muy por encima de la media de los \u00faltimos a\u00f1os y el desborde de una enorme presa en Camer\u00fan han provocado graves da\u00f1os en hogares, infraestructuras y en vast\u00edsimas extensiones de terreno dedicadas a la agricultura.<\/li>\n\n\n\n<li>\u00c1frica Occidental: En toda el \u00c1frica Occidental ha habido problemas graves con las inundaciones, que adem\u00e1s acarrean una consecuencia directa: la deforestaci\u00f3n.<\/li>\n\n\n\n<li>Sur de \u00c1frica: En diversos pa\u00edses del sur, incluidos Madagascar y Mozambique, ya se han producido este a\u00f1o seis fuertes tormentas que han causado el fallecimiento de casi 900 personas.<\/li>\n\n\n\n<li>Norte de \u00c1frica: en julio, T\u00fanez lleg\u00f3 a registrar temperaturas de 48 grados. Los episodios de calor extremo agravaron otro fen\u00f3meno: el de los incendios forestales. En Argelia, este verano contabilizaron una treintena de v\u00edctimas.<\/li>\n\n\n\n<li>Cuerno de \u00c1frica: Ya les he hablado en diversas ocasiones del impacto que la sequ\u00eda est\u00e1 teniendo en pa\u00edses como Somalia, con la peor hambruna de los \u00faltimos 40 a\u00f1os, que en estos momentos est\u00e1 matando ni\u00f1os y ni\u00f1as y forzando el desplazamiento de millones de personas que huyen de un terreno \u00e1rido, en el que la ganader\u00eda pr\u00e1cticamente ha desaparecido porque es imposible darle agua a los animales. La del cuerno de \u00c1frica, no lo olvidemos, es oficialmente la primera hambruna del mundo inducida por el cambio clim\u00e1tico.<\/li>\n\n\n\n<li>Sahel: Solo por ponerles un ejemplo, el <a href=\"https:\/\/www.icrc.org\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Comit\u00e9 Internacional de la Cruz Roja<\/a> alertaba esta misma semana de los efectos del cambio clim\u00e1tico en Mali, donde &#8220;lagos enteros&#8221; se han secado y la desertificaci\u00f3n se extiende, lo que ha rebajado hasta en un 10,5 % la producci\u00f3n de cereales en 2021, algo que afect\u00f3 directamente al sustento de tres millones de personas. En Chad, tambi\u00e9n, casi dos millones de personas se han visto directamente afectadas por inundaciones, en agosto y octubre.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto, pues, llegar\u00e1n a Egipto delegaciones de todos los pa\u00edses africanos, conjurados para tratar de alzar la voz y que esta COP sea la que, verdaderamente, fuerce a los pa\u00edses desarrollados a cumplir con las promesas que en anteriores reuniones se han ido realizando y, a\u00f1o tras a\u00f1o, se han incumplido sistem\u00e1ticamente. El ejemplo m\u00e1s claro es la promesa que hicieron los pa\u00edses de altos ingresos de desembolsar 100 000 millones de d\u00f3lares anuales en financiaci\u00f3n clim\u00e1tica para las naciones de bajos ingresos vulnerables al cambio clim\u00e1tico entre 2020 y 2025. \u00bfLa previsi\u00f3n de este a\u00f1o? Cerca de 20 000 millones. Ni una quinta parte de lo comprometido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque el mundo debe ser consciente de que el agravamiento de la situaci\u00f3n en \u00c1frica, es decir, lo que suceder\u00e1 en el caso de que no se apliquen medidas inmediatas para paliar los efectos del cambio clim\u00e1tico, no beneficiar\u00e1 a nadie: las hambrunas generan presiones sociales y econ\u00f3micas que amenazan con exacerbar las tensiones pol\u00edticas ya existentes. Y en ese r\u00edo revuelto hay ya varios pescadores aprovech\u00e1ndose de las ganancias. Miren si no a Rusia y su creciente influencia en el Sahel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De adaptaci\u00f3n clim\u00e1tica africana ir\u00e1 esta cumbre, que debe abordar medidas y ayudas para que los africanos puedan acelerar su acceso a la energ\u00eda sostenible. Y para muestra, un dato: el continente africano (1300 millones de personas) solo dispone en generaci\u00f3n de energ\u00eda el\u00e9ctrica un total de 108 gigavatios, la misma capacidad que un pa\u00eds como el Reino Unido (de 66 millones de habitantes).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque en estos momentos, el 75 % de los hombres y mujeres que en este planeta no tienen acceso a la electricidad est\u00e1n en alg\u00fan pa\u00eds de \u00c1frica subsahariana. Y aunque \u00c1frica solo sea el causante de un 4 % de las emisiones contaminantes en el planeta, este escaso acceso a la electricidad tambi\u00e9n tiene, a su manera, efectos contaminantes que deben ser frenados: desde la deforestaci\u00f3n que provoca la necesidad de madera para cocinar a la contaminaci\u00f3n que acarrea la absoluta dependencia de traer de fuera cualquier producto a trav\u00e9s del transporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta COP 27 llega, adem\u00e1s, en un momento parad\u00f3jico. Despu\u00e9s de a\u00f1os en que se le ha negado al continente africano la financiaci\u00f3n necesaria para empezar a explotar sus enormes reservas de gas, llega la guerra de Ucrania y, de golpe, los pa\u00edses europeos miran a \u00c1frica y le piden que acelere los proyectos para llevar el gas que ahora no le podemos (ni debemos) comprar a los rusos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, me resultaron m\u00e1s que significativas estas declaraciones del actual vicepresidente de Nigeria, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Yemi_Osinbajo\" target=\"_blank\" rel=\"noreferrer noopener\">Yemi Osinbajo<\/a>, en la revista <a href=\"https:\/\/www.foreignaffairs.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Foreign Affairs<\/a>: \u201cel uso de nuestra energ\u00eda, y por lo tanto nuestras emisiones, son tan bajos en \u00c1frica que incluso triplicar el consumo de electricidad a trav\u00e9s del gas natural solo a\u00f1adir\u00eda un 0,6 % a las emisiones globales\u201d. Quiz\u00e1s, pues, es hora de abrir un poco la mano con los pa\u00edses en desarrollo, a los que no se lo hemos permitido, al tiempo que somos firmes y audaces en medidas que permitan reducir las emisiones de los pa\u00edses m\u00e1s desarrollados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s importante, sin embargo, es que de esta cita de Egipto surjan compromisos claros de financiaci\u00f3n y ayudas a los pa\u00edses africanos para desarrollar con fuerza su mercado el\u00e9ctrico de la forma m\u00e1s sostenible posible, adem\u00e1s de medidas que permitan que \u00c1frica sea m\u00e1s resiliente a episodios como las inundaciones o las sequ\u00edas, que sin duda a partir de ahora van a ser constantes y peri\u00f3dicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ya el momento en que empiecen a surgir compromisos, por ejemplo, de favorecer que \u00c1frica se convierta en un productor de hidr\u00f3geno verde, el que sin duda es el combustible llamado a garantizar un mundo sin emisiones y, por lo tanto, en el que en el futuro puedan vivir sin morirse de calor o por fen\u00f3menos clim\u00e1ticos nuestros hijos y nietos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/casafrica.es\/es\/persona\/jose-segura-clavell\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Segura Clavell<\/a>, director general de Casa \u00c1frica, y publicado el 28 de octubre de 2022 en <a href=\"https:\/\/kioscoinsular.com\/criterios\/la-amenaza-climatica-no-es-futuro-ya-es-presente\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kiosco Insular<\/a> y el 30 de octubre de 2022 en <a href=\"https:\/\/www.canarias7.es\/opinion\/firmas\/amenaza-climatica-futuro-20221030020528-nt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Canarias7<\/a>.<\/em> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En poco m\u00e1s de una semana, Egipto acoger\u00e1 la COP27, la cumbre clim\u00e1tica en la que los pa\u00edses africanos exigir\u00e1n, y con raz\u00f3n, ayuda financiera y apoyo para hacer frente a unos fen\u00f3menos clim\u00e1ticos que ya est\u00e1 causando muertes, da\u00f1os y enormes p\u00e9rdidas Faltan ya muy pocos d\u00edas para que se celebre en Egipto, concretamente [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[82,263,384,2700,2699,2458,663,664,1054,2698,1490,1802,1880,2004],"class_list":["post-17309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilidad-energia-africa","tag-africa","tag-ayuda-humanitaria","tag-cambio-climatico","tag-compromiso","tag-deforestacion","tag-desastres-naturales","tag-desplazamientos-forzosos","tag-destacado","tag-hambruna","tag-incendios-forestales","tag-migracion","tag-politica","tag-recomendamos","tag-sequia"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=17309"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media\/17310"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=17309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=17309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=17309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}