{"id":17618,"date":"2023-04-24T10:55:16","date_gmt":"2023-04-24T09:55:16","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=17618"},"modified":"2025-09-18T10:46:48","modified_gmt":"2025-09-18T09:46:48","slug":"canarias-fundamental-para-el-programa-mundial-de-alimentos","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/pt-pt\/economia-desarrollo\/canarias-fundamental-para-el-programa-mundial-de-alimentos\/","title":{"rendered":"Canarias, fundamental para el Programa Mundial de Alimentos"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>La base del PMA en el puerto de Las Palmas es cada vez m\u00e1s importante para Naciones Unidas en su lucha contra las crisis alimentarias que afectan a varios pa\u00edses de nuestro entorno<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este pasado jueves, 20 de abril, <a href=\"https:\/\/casafrica.es\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Casa \u00c1frica<\/a> acogi\u00f3 un <a href=\"https:\/\/casafrica.es\/es\/evento\/seminario-canarias-en-el-pma\" target=\"_blank\" rel=\"noreferrer noopener\">acto<\/a> centrado en el papel que Canarias est\u00e1 jugando para el <a href=\"https:\/\/casafrica.es\/es\/redes\/programa-mundial-de-alimentos-0\" target=\"_blank\" rel=\"noreferrer noopener\">Programa Mundial de Alimentos<\/a> (PMA, o WFP por sus siglas en ingl\u00e9s) y organizado por el Consejo Canario del Movimiento Europeo, gracias al tes\u00f3n del profesor universitario <a href=\"https:\/\/spdc.ulpgc.es\/autor\/lucas-andres-perez-martin\/#:~:text=Secretario%20del%20Consejo%20Canario%20del,de%20la%20ULPGC%20desde%202009.\" target=\"_blank\" rel=\"noreferrer noopener\">Lucas P\u00e9rez Mart\u00edn<\/a>, secretario de dicho organismo y director del Campus Internacional de la <a href=\"https:\/\/www.ulpgc.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">ULPGC<\/a>. Desde la apertura de la base log\u00edstica, firmada en 2012, y con el apoyo financiero de la <a href=\"https:\/\/casafrica.es\/es\/redes\/agencia-espanola-de-cooperacion-internacional-para-el-desarrollo-aecid\" target=\"_blank\" rel=\"noreferrer noopener\">Agencia Espa\u00f1ola de Cooperaci\u00f3n Internacional para el Desarrollo (AECID)<\/a>, la base del PMA en el <a href=\"https:\/\/www.palmasport.es\/es\/puerto-de-las-palmas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Puerto de la Luz y de Las Palmas<\/a> ha dotado a nuestra comunidad aut\u00f3noma de un elemento que debe llenarnos de orgullo: junto al <a href=\"https:\/\/ccacr.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro de Cooperaci\u00f3n con \u00c1frica de la Cruz Roja<\/a>, nuestra tierra dispone de una plataforma excepcional de solidaridad con nuestros pa\u00edses vecinos. Y esto s\u00ed que es una forma de darle a Canarias el car\u00e1cter de plataforma log\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque creo que en nuestra tierra hay poca conciencia de lo que es y lo que supone tener esta base del Programa Mundial de Alimentos en un momento en el que es tan necesaria la actuaci\u00f3n inmediata en algunos de nuestros pa\u00edses vecinos. Y creo que es importante recordar y reconocer que entidades como la <a href=\"https:\/\/www.palmasport.es\/es\/autoridad-portuaria-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Autoridad Portuaria de Las Palmas<\/a>, u otra como la AECID (que en 2022 firm\u00f3 la renovaci\u00f3n del compromiso para cuatro a\u00f1os m\u00e1s con esta agencia de <a href=\"https:\/\/www.un.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Naciones Unidas<\/a>), han sido fundamentales para que la base canaria del PMA sea hoy \u201cuna pieza clave\u201d para la estrategia humanitaria internacional hacia todo el continente africano, especialmente para \u00c1frica occidental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que supimos el jueves a trav\u00e9s de estas jornadas s\u00ed es nuevo, y es que nos permitieron entender que la yuxtaposici\u00f3n de diversas crisis regionales humanitarias y alimentarias, el impacto de la guerra de Ucrania en la log\u00edstica mundial, el efecto que el cambio clim\u00e1tico est\u00e1 teniendo en el mercado alimentario y la propia din\u00e1mica de funcionamiento de varios puertos africanos de nuestro entorno son factores que han convencido al PMA de que su base en Las Palmas es, en estos momentos, \u201cla \u00fanica opci\u00f3n\u201d para lograr no solo que los alimentos lleguen a cualquier punto de \u00c1frica occidental en menos de un mes, sino para cumplir con su novedosa estrategia. Este nuevo concepto es algo que va m\u00e1s all\u00e1 de lo que esta agencia log\u00edstica siempre ha denominado el preposicionamiento de alimentos, y que ahora ha adquirido una nueva dimensi\u00f3n a trav\u00e9s del llamado \u201cMecanismo de Gesti\u00f3n Global de Alimentos\u201d (GCMF, por sus siglas en ingl\u00e9s), un proceso de financiaci\u00f3n interna que permite comprar con m\u00e1s antelaci\u00f3n y reducir as\u00ed el tiempo de entrega de la ayuda a los beneficiarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La responsable de este programa, Debora Debernardis, dio cifras de lo que pretenden que crezca el tr\u00e1fico de alimentos por la base del PMA en Las Palmas: si este a\u00f1o ya se han canalizado 30 000 toneladas m\u00e9tricas de alimentos (cifra que ya supera la de a\u00f1os anteriores), la aspiraci\u00f3n para el a\u00f1o pr\u00f3ximo pasa por canalizar 50 000 toneladas a trav\u00e9s de Las Palmas, una base que permite reducir a 30 d\u00edas el tiempo que se tarda en hacer llegar un env\u00edo a cualquiera de las conexiones que tiene con \u00c1frica occidental. En a\u00f1os anteriores, el PMA usaba puertos como el de Duala (Camer\u00fan) o Lom\u00e9 (Togo), pero los tiempos de env\u00edo raramente lograban bajar de los 120 d\u00edas, a los que se sumaban inconvenientes como la imposibilidad de manejar cargas grandes durante los meses de lluvias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debernardis explic\u00f3 que la base de Las Palmas no solo permite ahorrar costes y tiempo, sino que asegura tambi\u00e9n, por las magn\u00edficas condiciones de los almacenes, una conservaci\u00f3n perfecta de los alimentos. Por ello, desvel\u00f3 que en la nueva estrategia del PMA con Canarias se contemplar\u00e1 que siempre existan reservas de alimentos de, al menos, 5000 toneladas en cualquier momento. La clave del sistema del PMA es comprar los alimentos en periodo de cosecha (cuando su precio es m\u00e1s bajo) y almacenarlos para ir ajustando su distribuci\u00f3n en funci\u00f3n de las necesidades de cada crisis. Tener esa previsi\u00f3n no solo ahorra dinero, sino que evita beneficiar a diversos intermediarios que esperaban a vender los productos que almacenaban en \u00e9pocas de escasez para multiplicar su precio y, por lo tanto, su beneficio. No es mal momento para recordar, tambi\u00e9n, que, adem\u00e1s de la parte log\u00edstica, el PMA ha adquirido en los \u00faltimos a\u00f1os gofio a empresas canarias, que surte a algunos de los pa\u00edses del entorno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta jornada tuvimos el gran honor de reencontrarnos, aunque fuera virtualmente, con Pablo Yuste, brillante experto log\u00edstico espa\u00f1ol, actual coordinador del Programa Mundial de Alimentos en Nigeria y la persona que dirigi\u00f3 el establecimiento de la base del PMA en Canarias: de hecho, Yuste estuvo un a\u00f1o y medio trabajando desde un despacho en Casa \u00c1frica mientras avanzaban las obras de preparaci\u00f3n de las oficinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n, Yuste nos ense\u00f1\u00f3 a calibrar la magnitud del desastre cuando las grandes agencias humanitarias hablan del nivel 5 o de \u2018hambruna\u2019 en alg\u00fan pa\u00eds africano. Y nos puso un ejemplo bien claro: en situaci\u00f3n de hambruna, como la que est\u00e1 declarada en estos momentos en diversos puntos de \u00c1frica, cada d\u00eda mueren 2 personas de cada 10 000. As\u00ed que, por ejemplo, si la isla de Gran Canaria (850 000 personas) tuviese una situaci\u00f3n similar a la que ahora experimentan varias zonas de pa\u00edses africanos, morir\u00edan 170 personas al d\u00eda, una cifra que, en cualquier otra circunstancia, como bien dijo, \u201cnos helar\u00eda la sangre\u201d y provocar\u00eda la inmediata toma de decisiones pol\u00edticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso es tan importante que sigamos recordando frecuentemente que, en algunos puntos del continente, estamos presenciando la hambruna m\u00e1s grave vivida en varias d\u00e9cadas. El planteamiento realizado el jueves por los ponentes vinculados al PMA fue crudo: el mundo tiene cada vez m\u00e1s complicado alcanzar el <a href=\"https:\/\/www.fao.org\/sustainable-development-goals\/goals\/goal-2\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Objetivo de Hambre Cero<\/a> que plantea la <a href=\"https:\/\/unric.org\/es\/agenda-2030\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agenda 2030<\/a> de las Naciones Unidas, ya que en estos momentos hasta 1300 millones de personas viven en situaci\u00f3n de lo que los expertos llaman \u201cpobreza multidimensional\u201d en hasta 109 pa\u00edses diferentes. Y esa suma de crisis de la que les hablaba antes, la de los sistemas alimentarios, la clim\u00e1tica, la guerra de Ucrania (pa\u00eds que era el primer proveedor de grano del PMA), no hacen sino complicarlo todo un poco m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n es de una gravedad extrema en varios pa\u00edses, mayoritariamente africanos (la franja de pa\u00edses del Sahel, el noreste de Nigeria, Somalia, Etiop\u00eda), pero tambi\u00e9n en pa\u00edses azotados por conflictos como Yemen o Afganist\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este pr\u00f3ximo jueves, 27 de abril, en Casa \u00c1frica, profundizaremos sobre las crisis alimentarias, un tema al que debemos todos estar atentos, como ya he preconizado en muchas ocasiones. Aprovechando la reuni\u00f3n de los miembros de la Asociaci\u00f3n de Sociedades Nacionales de la Cruz Roja y de la Media Luna Roja Franc\u00f3fonas, Lus\u00f3fonas e Hispan\u00f3fonas de \u00c1frica (ACROFA) en la capital grancanaria, ofrecemos nuestra sede para organizar conjuntamente con ellos, el Centro de Cooperaci\u00f3n con \u00c1frica de la Cruz Roja espa\u00f1ola y el Programa Mundial de Alimentos (WFP-PMA) un <a href=\"https:\/\/casafrica.es\/es\/evento\/seminariocrisis-alimentarias-en-africa-retos-y-experiencias\" target=\"_blank\" rel=\"noreferrer noopener\">seminario<\/a> que se centrar\u00e1 en analizar los desaf\u00edos de la ayuda humanitaria en \u00c1frica en nuestros d\u00edas y, especialmente, en las emergencias humanitarias complejas relacionadas con la inseguridad alimentaria y la hambruna en el Sahel y el Cuerno de \u00c1frica, debatiendo y exponiendo desaf\u00edos, soluciones y perspectivas de futuro de la situaci\u00f3n en ambas emergencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acto nos pondr\u00e1 en situaci\u00f3n sobre el impacto de las principales crisis alimentarias en \u00c1frica y tendr\u00e1 lugar por la ma\u00f1ana, en abierto, <em>online<\/em> y presencial, as\u00ed que no hay excusa para \u2013si le interesa el tema- no seguirlo. Combinar\u00e1 desaf\u00edos y oportunidades desde el punto de vista t\u00e9cnico con experiencias, como las de la denominada Mama Dimanche (Mam\u00e1 Domingo), el apelativo cari\u00f1oso de la se\u00f1ora <a href=\"https:\/\/casafrica.es\/es\/persona\/christine-ntahe\" target=\"_blank\" rel=\"noreferrer noopener\">Christine Ntahe<\/a>, presidenta de Cruz Roja en Burundi y de la ACROFA y fundadora de la fundaci\u00f3n que se preocupa de la alimentaci\u00f3n de los ni\u00f1os en su pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siempre he escrito en estos art\u00edculos lo importante que es que hablemos y conozcamos las situaciones m\u00e1s extremas de crisis que vive nuestro planeta. El jueves, Pablo Yuste le puso a esta reflexi\u00f3n las palabras precisas: \u201cDe lo que no se habla no existe, y ante lo que no existe no se act\u00faa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/casafrica.es\/es\/persona\/jose-segura-clavell\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Segura Clavell<\/a>, director general de Casa \u00c1frica, y publicado el 21 de abril de 2023 en <a href=\"https:\/\/www.eldiario.es\/canariasahora\/canarias-opina\/canarias-fundamental-programa-mundial-alimentos_132_10141371.html\" target=\"_blank\" rel=\"noreferrer noopener\">eldiario.es<\/a> y en <a href=\"https:\/\/kioscoinsular.com\/portada\/canarias-fundamental-para-el-programa-mundial-de-alimentos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kiosco Insular<\/a> y el 22 de abril de 2023 en <a href=\"https:\/\/www.canarias7.es\/opinion\/jose-segura-clavell-canarias-fundamental-programa-mundial-alimentos-20230422125447-nt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Canarias7<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La base del PMA en el puerto de Las Palmas es cada vez m\u00e1s importante para Naciones Unidas en su lucha contra las crisis alimentarias que afectan a varios pa\u00edses de nuestro entorno Este pasado jueves, 20 de abril, Casa \u00c1frica acogi\u00f3 un acto centrado en el papel que Canarias est\u00e1 jugando para el Programa [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[133,170,2812,541,575,2481,580,2813,644,2814,664,1054,1601,1674,3015,1880],"class_list":["post-17618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-desarrollo","tag-agenda-2030","tag-alimentacion","tag-base-logistica","tag-cooperacion","tag-crisis","tag-crisis-alimentaria","tag-crisis-humanitaria","tag-crisis-regional","tag-derechos-humanos","tag-desafios","tag-destacado","tag-hambruna","tag-naciones-unidas","tag-ods","tag-oportunidades","tag-recomendamos"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=17618"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media\/17620"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=17618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=17618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=17618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}