{"id":17908,"date":"2023-07-20T12:10:43","date_gmt":"2023-07-20T11:10:43","guid":{"rendered":"https:\/\/www.esafrica.es\/?p=17908"},"modified":"2023-07-21T11:03:47","modified_gmt":"2023-07-21T10:03:47","slug":"los-paises-de-africa-occidental-demuestran-como-trabajar-juntos-durante-decadas-construye-la-paz-y-cesa-el-estallido-de-las-guerras","status":"publish","type":"post","link":"https:\/\/www.esafrica.es\/pt-pt\/politica-geopolitica\/los-paises-de-africa-occidental-demuestran-como-trabajar-juntos-durante-decadas-construye-la-paz-y-cesa-el-estallido-de-las-guerras\/","title":{"rendered":"Los pa\u00edses de \u00c1frica Occidental demuestran c\u00f3mo trabajar juntos durante d\u00e9cadas construye la paz y cesa el estallido de las guerras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A menudo, \u00c1frica es representada como un continente devastado por la guerra, el terrorismo, la pobreza y la inestabilidad pol\u00edtica. Sin embargo, en las \u00faltimas cinco d\u00e9cadas han acontecido escasos conflictos violentos entre los Estados, en comparaci\u00f3n con Europa, donde han ocurrido desde 1945 m\u00e1s de 25 conflictos interestatales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es verdad que \u00c1frica ha sido testigo de <a href=\"https:\/\/projects.voanews.com\/african-coups\/\" target=\"_blank\" rel=\"noreferrer noopener\">214<\/a> golpes de Estado, la mayor cantidad de cualquier regi\u00f3n, y 106 han tenido \u00e9xito. De los <a href=\"https:\/\/projects.voanews.com\/african-coups\/\" target=\"_blank\" rel=\"noreferrer noopener\">54 pa\u00edses<\/a> del continente africano, 45 han afrontado desde 1950 al menos un intento de golpe de Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1frica Occidental es una regi\u00f3n de 16 Estados independientes y ha <a href=\"https:\/\/projects.voanews.com\/african-coups\/\" target=\"_blank\" rel=\"noreferrer noopener\">experimentado<\/a> 53 golpes de Estado exitosos y 40 fallidos desde 1950. Tambi\u00e9n, existen problemas de seguridad transfronterizos como el terrorismo, el bandolerismo, la pirater\u00eda y la gran presencia de <a href=\"https:\/\/theconversation.com\/west-africa-has-a-small-weapons-crisis-why-some-countries-are-better-at-dealing-with-it-than-others-203085\" target=\"_blank\" rel=\"noreferrer noopener\">armas<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, desde su independencia a finales de los a\u00f1os 50, los pa\u00edses de la regi\u00f3n no se han enfrentado entre s\u00ed, excepto por un enfrentamiento armado menor en 1985 entre Burkina Faso y Mali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un reciente art\u00edculo estudiamos las posibles razones de esto. Como investigadores, analizamos la din\u00e1mica pol\u00edtica de \u00c1frica Occidental y llegamos a nuestras conclusiones gracias al an\u00e1lisis de datos hist\u00f3ricos, interacciones diplom\u00e1ticas e investigaci\u00f3n acad\u00e9mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hallamos pruebas de que las relaciones entre los pa\u00edses de \u00c1frica Occidental son definidas por los principios de no agresi\u00f3n y de arreglo pac\u00edfico de controversias. Los 15 Estados bajo <a href=\"https:\/\/ecowas.int\/wp-content\/uploads\/2022\/08\/Revised-treaty-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">la protecci\u00f3n<\/a> de la Comunidad Econ\u00f3mica de los Estados de \u00c1frica Occidental (CEDEAO) se identifican de forma positiva con el destino de otros en el bloque. En 1975, este organismo regional fue creado por los pa\u00edses de \u00c1frica Occidental para promover el desarrollo econ\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encontramos una fuerte correlaci\u00f3n entre d\u00e9cadas de cooperaci\u00f3n regional y la escasez de los conflictos entre los Estados de \u00c1frica Occidental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concluimos que la cooperaci\u00f3n sist\u00e9mica entre los Estados de la regi\u00f3n ha dado lugar a una identidad colectiva que se ha formado con el tiempo. Se ha desarrollado un sentido de comunidad. La comunidad ha fomentado mecanismos de gesti\u00f3n de conflictos impidiendo as\u00ed que los miembros entren en guerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta conclusi\u00f3n destaca la importancia de la colaboraci\u00f3n y la diplomacia con el fin de mantener la paz y resolver los conflictos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CEDEAO: dar valor a su paz<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los conflictos son determinados por la din\u00e1mica regional y los factores, como se puede observar en el Cuerno de \u00c1frica. Esa regi\u00f3n, por ejemplo, ha sido testigo de conflictos entre Etiop\u00eda y Eritrea y entre Etiop\u00eda y Somalia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la regi\u00f3n de \u00c1frica Occidental descubrimos que las medidas de seguridad establecidas en el marco de la CEDEAO han contribuido a fomentar la paz entre los Estados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1993 se actualiz\u00f3 el <a href=\"https:\/\/ecowas.int\/wp-content\/uploads\/2022\/08\/Revised-treaty-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">acuerdo de la CEDEAO<\/a> e incluye principios que estaban ausentes en el pacto anterior. Entre ellos figuran:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>solidaridad y autonom\u00eda colectiva<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>no agresi\u00f3n entre los Estados miembros<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>promoci\u00f3n y fortalecimiento de las buenas relaciones para mantener la paz, la estabilidad y la seguridad regional<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>soluci\u00f3n pac\u00edfica de controversias entre los Estados miembros<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>cooperaci\u00f3n activa entre pa\u00edses vecinos<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la promoci\u00f3n de un entorno pac\u00edfico como un requisito previo para el desarrollo econ\u00f3mico.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esto ha llevado a los pa\u00edses de \u00c1frica Occidental a elegir la resoluci\u00f3n pac\u00edfica de controversia en lugar de la soberan\u00eda. Por ejemplo, en 2017 se resolvi\u00f3 un <a href=\"https:\/\/foleyhoag.com\/news-and-insights\/news\/2017\/september\/ghana-wins-maritime-boundary-dispute-against-cote-divoire\/\" target=\"_blank\" rel=\"noreferrer noopener\">conflicto fronterizo<\/a> entre Ghana y Costa de Marfil a trav\u00e9s de un tribunal internacional. Este enfoque ha evitado conflictos violentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un factor clave es que los Estados miembros cuentan con mecanismos para resolver los conflictos de forma pac\u00edfica. En las guerras de <a href=\"http:\/\/www.peacebuildingdata.org\/research\/liberia\/results\/civil-war\/root-causes-civil-war\" target=\"_blank\" rel=\"noreferrer noopener\">Liberia<\/a> y <a href=\"http:\/\/peri.umass.edu\/fileadmin\/pdf\/Sierraleone.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sierra Leona<\/a>, que amenazaban con involucrar a otros pa\u00edses de la regi\u00f3n, la CEDEAO emple\u00f3 estos mecanismos de resoluci\u00f3n. Despleg\u00f3 tropas militares para supervisar los <a href=\"https:\/\/www.accord.org.za\/ajcr-issues\/peace-agreements-and-the-termination-of-civil-wars\/\" target=\"_blank\" rel=\"noreferrer noopener\">alto el fuego<\/a> negociados por el entonces <a href=\"https:\/\/theconversation.com\/some-ghanaians-hate-him-some-love-him-the-mixed-legacy-of-jerry-john-rawlings-163310\" target=\"_blank\" rel=\"noreferrer noopener\">presidente<\/a> de Ghana, <a href=\"https:\/\/theconversation.com\/some-ghanaians-hate-him-some-love-him-the-mixed-legacy-of-jerry-john-rawlings-163310\" target=\"_blank\" rel=\"noreferrer noopener\">Jerry Rawlings<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro factor es lo que en nuestro an\u00e1lisis llamamos panafricanismo occidental. Lo describimos como una versi\u00f3n regional del panafricanismo que enfatiza la unidad y la colaboraci\u00f3n entre pa\u00edses. En la pr\u00e1ctica, ha facilitado los intercambios comerciales, culturales y diplom\u00e1ticos. Tambi\u00e9n ha dado origen a un sentido de identidad compartida y solidaridad entre los pa\u00edses miembros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostenemos que la idea del panafricanismo occidental ha promovido la solidaridad regional y ha reducido la posibilidad de violencia en las relaciones interestatales. No es solo una filosof\u00eda, sino un enfoque pr\u00e1ctico de la integraci\u00f3n y la cooperaci\u00f3n regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro art\u00edculo respalda el argumento de que la cooperaci\u00f3n sist\u00e9mica entre los Estados puede llevar a la formaci\u00f3n de una identidad colectiva a lo largo del tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto ha sucedido con la Uni\u00f3n Europea, la Organizaci\u00f3n del Tratado del Atl\u00e1ntico del Norte y la Asociaci\u00f3n de Naciones del Asia Sudoriental. Sus identidades colectivas se basan en normas que reflejan la historia y las culturas pol\u00edticas de sus Estados miembros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A menudo se pasa por alto la importancia de la identidad compartida y la convivencia pac\u00edfica al explicar las complejas relaciones internacionales, pero es esencial para comprender las relaciones de los Estados de \u00c1frica Occidental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Art\u00edculo redactado por <a href=\"https:\/\/theconversation.com\/profiles\/abubakar-abubakar-usman-1439849\" target=\"_blank\" rel=\"noreferrer noopener\">Abubakar Abubakar Usman<\/a><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El art\u00edculo fue publicado originalmente en ingl\u00e9s por <a href=\"https:\/\/theconversation.com\/west-african-countries-show-how-working-together-over-decades-builds-peace-and-stops-wars-breaking-out-205498\" target=\"_blank\" rel=\"noreferrer noopener\">The Conversation<\/a> el 31 de mayo de 2023 y traducido al espa\u00f1ol con la colaboraci\u00f3n de Casa \u00c1frica. Traducci\u00f3n realizada por Luc\u00eda Saucedo.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A menudo, \u00c1frica es representada como un continente devastado por la guerra, el terrorismo, la pobreza y la inestabilidad pol\u00edtica. Sin embargo, en las \u00faltimas cinco d\u00e9cadas han acontecido escasos conflictos violentos entre los Estados, en comparaci\u00f3n con Europa, donde han ocurrido desde 1945 m\u00e1s de 25 conflictos interestatales. Es verdad que \u00c1frica ha sido [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[420,507,525,664,1041,1107,1729,2435,2381,1880,2123],"class_list":["post-17908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-geopolitica","tag-cedeao","tag-comercio-transfronterizo","tag-conflictos","tag-destacado","tag-guerra","tag-identidad","tag-panafricanismo","tag-paz-y-seguridad","tag-politica-3","tag-recomendamos","tag-the-conversation"],"_links":{"self":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=17908"}],"version-history":[{"count":0,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/posts\/17908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media\/17910"}],"wp:attachment":[{"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=17908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=17908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esafrica.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=17908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}